{"id":15065,"date":"2024-02-27T19:12:04","date_gmt":"2024-02-27T18:12:04","guid":{"rendered":"https:\/\/alertes-meteo.com\/?p=15065"},"modified":"2024-02-27T19:14:20","modified_gmt":"2024-02-27T18:14:20","slug":"flocons-de-neige-a-un-niveau-microscopique","status":"publish","type":"post","link":"https:\/\/alertes-meteo.com\/index.php\/2024\/02\/27\/flocons-de-neige-a-un-niveau-microscopique\/","title":{"rendered":"Flocons de neige \u00e0 un niveau microscopique"},"content":{"rendered":"<p>Le photographe et scientifique Nathan Myhrvold a d\u00e9velopp\u00e9 un appareil photo qui capture les flocons de <a href=\"https:\/\/alertes-meteo.com\/index.php\/2024\/02\/15\/formation-de-la-neige\/\">neige<\/a> \u00e0 un niveau microscopique jamais vu auparavant. Il a r\u00e9cemment publi\u00e9 une s\u00e9rie d&rsquo;images prises avec sa cr\u00e9ation, un prototype qui capture les flocons de neige \u00e0 un niveau microscopique in\u00e9dit. Myhrvold, qui d\u00e9tient un doctorat en math\u00e9matiques th\u00e9oriques et en physique de l&rsquo;Universit\u00e9 de Princeton et qui a \u00e9t\u00e9 le directeur de la technologie chez Microsoft, s&rsquo;est appuy\u00e9 sur son exp\u00e9rience de scientifique pour cr\u00e9er cet appareil photo. Il a \u00e9galement utilis\u00e9 son exp\u00e9rience de photographe, notamment en tant que fondateur de Modernist Cuisine, un laboratoire d&rsquo;innovation culinaire connu pour ses photographies haute r\u00e9solution de divers aliments publi\u00e9es dans un livre en cinq volumes.<\/p>\n<p>La photographie de flocons de neige n&rsquo;est pas nouvelle. Dans les ann\u00e9es 1880, un fermier du Vermont nomm\u00e9 Wilson Bentley a commenc\u00e9 \u00e0 photographier des flocons de neige \u00e0 un niveau microscopique sur sa ferme. Aujourd&rsquo;hui, il est consid\u00e9r\u00e9 comme un pionnier pour son travail, qui fait partie des archives de la Smithsonian Institution. Ses photographies sont consid\u00e9r\u00e9es comme l&rsquo;inspiration pour la sagesse commune que \u00ab\u00a0aucun flocon de neige n&rsquo;est identique\u00a0\u00bb. Plus d&rsquo;un si\u00e8cle plus tard, le domaine de la photographie de flocons de neige a continu\u00e9 \u00e0 \u00e9voluer, comme en t\u00e9moignent les images haute r\u00e9solution que Myhrvold a produites avec son propre appareil photo.<\/p>\n<p>Pour surmonter le d\u00e9fi de la tendance des flocons de neige \u00e0 se d\u00e9sint\u00e9grer rapidement, Myhrvold a \u00e9quip\u00e9 son syst\u00e8me de cam\u00e9ra de 60 \u20ac avec un syst\u00e8me de refroidissement thermo\u00e9lectrique, un cadre en fibre de carbone et des lumi\u00e8res LED, qui d\u00e9gagent moins de chaleur que les lumi\u00e8res standard. Chaque partie de son dispositif, qui mesure environ cinq pieds de hauteur lorsqu&rsquo;il est plac\u00e9 sur une table, a \u00e9t\u00e9 con\u00e7ue pour travailler en tandem pour capturer une image d&rsquo;un flocon de neige.<\/p>\n<p>Kenneth G. Libbrecht, professeur de physique au CalTech qui a \u00e9tudi\u00e9 en profondeur la physique et la formation des motifs de la glace, et dont le travail a inspir\u00e9 Myhrvold \u00e0 poursuivre ce projet, a \u00e9galement cr\u00e9\u00e9 un dispositif similaire pour ses propres recherches. Outre lui-m\u00eame, il dit que seuls Myhrvold et un photographe canadien nomm\u00e9 Don Komarechka ont accompli l&rsquo;exploit de photographier des flocons de neige.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le photographe et scientifique Nathan Myhrvold a d\u00e9velopp\u00e9 un appareil  [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":15070,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"none","_seopress_titles_title":"D\u00e9couvrez la photographie de flocons de neige microscopique de Nathan Myhrvold","_seopress_titles_desc":"D\u00e9couvrez les images microscopiques in\u00e9dites de flocons de neige captur\u00e9es par le photographe et scientifique Nathan Myhrvold, une avanc\u00e9e remarquable dans la photographie de flocons de neige.","_seopress_robots_index":"","_seopress_analysis_target_kw":"","footnotes":""},"categories":[80],"tags":[],"class_list":["post-15065","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"_links":{"self":[{"href":"https:\/\/alertes-meteo.com\/index.php\/wp-json\/wp\/v2\/posts\/15065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alertes-meteo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alertes-meteo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alertes-meteo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/alertes-meteo.com\/index.php\/wp-json\/wp\/v2\/comments?post=15065"}],"version-history":[{"count":0,"href":"https:\/\/alertes-meteo.com\/index.php\/wp-json\/wp\/v2\/posts\/15065\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alertes-meteo.com\/index.php\/wp-json\/wp\/v2\/media\/15070"}],"wp:attachment":[{"href":"https:\/\/alertes-meteo.com\/index.php\/wp-json\/wp\/v2\/media?parent=15065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alertes-meteo.com\/index.php\/wp-json\/wp\/v2\/categories?post=15065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alertes-meteo.com\/index.php\/wp-json\/wp\/v2\/tags?post=15065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}