{"id":14826,"date":"2024-02-22T21:00:08","date_gmt":"2024-02-22T20:00:08","guid":{"rendered":"https:\/\/alertes-meteo.com\/?p=14826"},"modified":"2024-02-25T21:26:59","modified_gmt":"2024-02-25T20:26:59","slug":"tempete-du-26-decembre-1999-chronique-dune-tempete-exceptionnelle-mal-annoncee","status":"publish","type":"post","link":"https:\/\/alertes-meteo.com\/index.php\/2024\/02\/22\/tempete-du-26-decembre-1999-chronique-dune-tempete-exceptionnelle-mal-annoncee\/","title":{"rendered":"Temp\u00eate du 26 d\u00e9cembre 1999 &#8211; Chronique d\u2019une temp\u00eate exceptionnelle mal annonc\u00e9e"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1302px;margin-left: calc(-5% \/ 2 );margin-right: calc(-5% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:2.375%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:2.375%;--awb-width-medium:100%;--awb-spacing-right-medium:2.375%;--awb-spacing-left-medium:2.375%;--awb-width-small:100%;--awb-spacing-right-small:2.375%;--awb-spacing-left-small:2.375%;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p><strong>Chronique d\u2019une temp\u00eate exceptionnelle mal annonc\u00e9e<\/strong><\/p>\n<p>D\u2019une ampleur exceptionnelle, la temp\u00eate qui a ravag\u00e9 le nord de l\u2019Europe a laiss\u00e9 M\u00e9t\u00e9o France pantois. L\u2019organisme m\u00e9t\u00e9orologique n\u2019a pas pu pr\u00e9voir ce que certains qualifient d\u2019historique ou exceptionnelle, ou de ph\u00e9nom\u00e8ne \u00e0 l\u2019extr\u00eame du possible en Europe. M\u00e9t\u00e9o-France n&rsquo;avait pas pris la mesure de l\u2019ampleur du d\u00e9sastre, ne parlant que d\u2019orages violents. Mais lundi, l\u2019institut d\u00e9nonce comme \u00ab\u00a0sans fondement\u00a0\u00bb des \u00ab\u00a0informations de presse\u00a0\u00bb mettant en cause sa rapidit\u00e9 dans la diffusion des messages d&rsquo;alerte. Chronique d\u2019une temp\u00eate mal annonc\u00e9e.<\/p>\n<p><strong>Jeudi 23 d\u00e9cembre &#8211; Temp\u00eate sur le nord et le nord-ouest de la France<\/strong><\/p>\n<p>Les premi\u00e8res pr\u00e9visions de temp\u00eate de M\u00e9t\u00e9o-France datent du jeudi 23 d\u00e9cembre. L\u2019organisme m\u00e9t\u00e9orologique pr\u00e9voyait alors \u00ab\u00a0une temp\u00eate sur le nord et le nord-ouest de la France, d\u00e8s la nuit de jeudi \u00e0 vendredi\u00a0\u00bb. La temp\u00eate devait toucher la Bretagne, le Pays de la Loire, le bassin parisien et le Nord Pas-de-Calais, et se renforcer tr\u00e8s vite dans la nuit, pour atteindre jusqu&rsquo;\u00e0 120 km pr\u00e8s des c\u00f4tes, 100 km\/h dans l&rsquo;int\u00e9rieur des terres.<\/p>\n<p><strong>Vendredi 24 d\u00e9cembre &#8211; Vent violent : alerte m\u00e9t\u00e9o en \u00cele-de-France<\/strong><\/p>\n<p>La veille de No\u00ebl, l\u2019alerte m\u00e9t\u00e9o est lanc\u00e9e. Elle sera la seule et unique, lanc\u00e9e par le Centre R\u00e9gional d\u2019informations routi\u00e8res, le CRIR de Cr\u00e9teil, pour \u00cele-de-France, pour la nuit de vendredi \u00e0 samedi. Le Centre pr\u00e9voit des rafales de vent \u00ab\u00a0pouvant atteindre 115km\/h\u00a0\u00bb et incite vivement les habitants de la r\u00e9gion parisienne \u00e0 une \u00ab\u00a0vigilance accrue\u00a0\u00bb. Mercredi 29 d\u00e9cembre, M\u00e9t\u00e9o-France a inform\u00e9 \u00e0 TF1, par la voix de son P.d.g. Jean-Pierre Beysson, que le bulletin d&rsquo;alerte du CRIR n&rsquo;est \u00ab\u00a0\u00e9mis que gr\u00e2ce au bulletin m\u00e9t\u00e9orologique transmis par M\u00e9t\u00e9o-France \u00e0 cet organisme\u00a0\u00bb. Or, si M\u00e9t\u00e9o-France pr\u00e9voyait de fortes rafales de vent, pourquoi ne pas en avoir pr\u00e9venu, \u00e0 temps, (hormis le CRIR) l&rsquo;AFP ou tout autre organe de presse ?<\/p>\n<p>Attention aux coups de vent samedi<\/p>\n<p>Vendredi M\u00e9t\u00e9o-France annon\u00e7ait de \u00ab\u00a0tr\u00e8s fortes vagues\u00a0\u00bb sur l\u2019Atlantique et sur la Manche jusqu&rsquo;\u00e0 lundi, et demandait aux habitants de faire attention aux coups de vent samedi, soufflant encore sur une bonne partie du pays, et d\u00e9passant les 100 km\/h dans la nuit. M\u00e9t\u00e9o-France pr\u00e9voyait une nuit plut\u00f4t agit\u00e9e. Le vent fort de secteur sud-ouest qui touche la moiti\u00e9 nord du pays atteindra parfois les 130 km\/h en rafales sur les c\u00f4tes de Manche et en Bretagne. Pluies diluviennes et vent violent attendus sur le Nord-Pas-de-Calais.<\/p>\n<p><strong>Samedi 25 d\u00e9cembre 1999 : orages violents sur le nord du pays<\/strong><\/p>\n<p>La temp\u00eate soufflait d\u00e9j\u00e0 fort samedi. M\u00e9t\u00e9o-France annon\u00e7ait une temp\u00eate dimanche sur les c\u00f4tes de la Manche et atlantiques, et une pluie s\u2019abattant sur toute la France. Apr\u00e8s une accalmie au d\u00e9but de la nuit, l&rsquo;organisme pr\u00e9voyait un vent soufflant jusqu&rsquo;aux premi\u00e8res heures du jour, avec des rafales atteignant jusqu&rsquo;\u00e0 140 km\/h sur le littoral. Un bulletin d\u2019alerte concernait 11 d\u00e9partements Nord, Pas-de-Calais, Somme, Aisne, Oise, Ardennes, Marne, Haute-Marne, Aube, Seine-Maritime et Eure. Ainsi, 24 heures \u00e0 l&rsquo;avance, M\u00e9t\u00e9o-France annon\u00e7ait bel et bien une temp\u00eate, mais les rafales de vent ont atteint, dimanche, des vitesses record, loin des pr\u00e9visions de l&rsquo;Institut : 173 km\/h en \u00cele-de-France par exemple, ou encore 184 km\/h sur \u00cele d&rsquo;Ouessant&#8230; Le P.d.g. de M\u00e9t\u00e9o-France, Jean-Pierre Beysson, a expliqu\u00e9 \u00e0 e-TF1 que \u00ab\u00a0les messages de temp\u00eate sont tout \u00e0 fait exceptionnels en zone de plaine\u00a0\u00bb. Et a accord\u00e9 que \u00ab\u00a0si ces valeurs ont \u00e9t\u00e9 sous-estim\u00e9es, elles atteignaient des records absolus\u00a0\u00bb. Face aux mises en cause, M\u00e9t\u00e9o-France estime avoir \u00ab\u00a0malgr\u00e9 tout annonc\u00e9 une temp\u00eate 24h \u00e0 l&rsquo;avance\u00a0\u00bb.<\/p>\n<p><strong>Dimanche 26 d\u00e9cembre 1999 : la temp\u00eate laisse derri\u00e8re elle un spectacle de d\u00e9solation<\/strong><\/p>\n<p>D\u2019une ampleur exceptionnelle, du jamais vu estiment certains m\u00e9t\u00e9orologistes, la temp\u00eate a balay\u00e9 aux premi\u00e8res heures du jour la partie nord de l\u2019Europe, en un rien de temps. En France, la temp\u00eate fera 70 morts. Des vitesse de vent record, s\u2019accorde-t-on \u00e0 dire. Un \u00ab\u00a0ph\u00e9nom\u00e8ne \u00e0 l&rsquo;extr\u00eame du possible en Europe\u00a0\u00bb, indique un pr\u00e9visionniste de M\u00e9t\u00e9o-France \u00e0 Toulouse. l&rsquo;organisme avait minimis\u00e9 l\u2019ampleur du d\u00e9sastre, ne parlant que d\u2019orages violents avec des vents de 130 km\/h au plus.<\/p>\n<p>Pour Hubert Brunet, chef pr\u00e9visionniste \u00e0 Toulouse, cette d\u00e9pression est qualifi\u00e9e d&rsquo;historique et exceptionnelle, notamment en \u00cele-de-France La Direction de la s\u00e9curit\u00e9 civile d\u00e9conseillait aux habitants de sortir dimanche \u00e0 cause des intemp\u00e9ries. Le vent soufflait toujours en rafales &#8211; certaines atteignant 170 km\/h &#8211; avec de la pluie.<\/p>\n<p>\u00c0 l&rsquo;\u00e9poque, le syst\u00e8me d&rsquo;alerte et de communication \u00e9tait critiqu\u00e9 pour son inefficacit\u00e9 et son manque de fiabilit\u00e9. Les populations touch\u00e9es \u00e9taient mal inform\u00e9es sur la gravit\u00e9 des situations et les mesures \u00e0 prendre pour se prot\u00e9ger, r\u00e9v\u00e9lant ainsi une coordination insuffisante entre les services d&rsquo;urgence et les autorit\u00e9s locales. Suite \u00e0 ces \u00e9v\u00e9nements tragiques, des r\u00e9formes ont \u00e9t\u00e9 entreprises pour renforcer le syst\u00e8me de pr\u00e9vention et de gestion des risques m\u00e9t\u00e9orologiques en France. M\u00e9t\u00e9o France a r\u00e9vis\u00e9 ses proc\u00e9dures d&rsquo;alerte et mis en place un syst\u00e8me de vigilance m\u00e9t\u00e9orologique.<\/p>\n<p><strong>Lundi 27 d\u00e9cembre 1999 : la deuxi\u00e8me temp\u00eate mieux annonc\u00e9e<\/strong><\/p>\n<p>D\u00e8s lundi matin (8h55), M\u00e9t\u00e9o-France annon\u00e7ait une deuxi\u00e8me temp\u00eate dans la soir\u00e9e sur le sud de la France, notamment sur le littoral de l&rsquo;Aquitaine \u00e0 Midi-Pyr\u00e9n\u00e9es, avec des vents de 110 \u00e0 140 km\/h, et des pointes de 150 km\/h. Cette deuxi\u00e8me temp\u00eate a \u00e9t\u00e9 mieux annonc\u00e9e par M\u00e9t\u00e9o-France.<\/p>\n<p><a href=\"https:\/\/alertes-meteo.com\/index.php\/2024\/02\/22\/tempete-du-27-decembre-1999\/\" style=\"font-family: var(--awb-text-font-family); font-size: var(--awb-font-size); font-style: var(--awb-text-font-style); font-weight: var(--awb-text-font-weight); letter-spacing: var(--awb-letter-spacing); text-align: var(--awb-content-alignment); text-transform: var(--awb-text-transform); background-color: var(--awb-bg-color-hover);\">Chronologie de la temp\u00eate Martin<\/a><\/p>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":14866,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"none","_seopress_titles_title":"Chronique d&#039;une Temp\u00eate mal annonc\u00e9e : M\u00e9t\u00e9o France sous le feu","_seopress_titles_desc":"D\u00e9couvrez comment M\u00e9t\u00e9o France a mal pr\u00e9vu l&#039;ampleur de la temp\u00eate exceptionnelle qui a ravag\u00e9 le nord de l&#039;Europe. Une histoire d&#039;alertes m\u00e9t\u00e9orologiques manqu\u00e9es.","_seopress_robots_index":"","_seopress_analysis_target_kw":"temp\u00eate Lothar,temp\u00eate lothar et martin,temp\u00eate lothar suisse,tempete lothar alsace,tempete lothar bretagne,temp\u00eate lothar paris,tempete lothar belgique,tempete lothar 99,tempete lothar mort","footnotes":""},"categories":[142],"tags":[151,143],"class_list":["post-14826","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-catastrophe","tag-tempete","tag-vent"],"_links":{"self":[{"href":"https:\/\/alertes-meteo.com\/index.php\/wp-json\/wp\/v2\/posts\/14826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alertes-meteo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alertes-meteo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alertes-meteo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/alertes-meteo.com\/index.php\/wp-json\/wp\/v2\/comments?post=14826"}],"version-history":[{"count":0,"href":"https:\/\/alertes-meteo.com\/index.php\/wp-json\/wp\/v2\/posts\/14826\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alertes-meteo.com\/index.php\/wp-json\/wp\/v2\/media\/14866"}],"wp:attachment":[{"href":"https:\/\/alertes-meteo.com\/index.php\/wp-json\/wp\/v2\/media?parent=14826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alertes-meteo.com\/index.php\/wp-json\/wp\/v2\/categories?post=14826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alertes-meteo.com\/index.php\/wp-json\/wp\/v2\/tags?post=14826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}