{"id":14801,"date":"2024-02-21T19:39:55","date_gmt":"2024-02-21T18:39:55","guid":{"rendered":"https:\/\/alertes-meteo.com\/?p=14801"},"modified":"2024-02-21T19:47:28","modified_gmt":"2024-02-21T18:47:28","slug":"le-ciel-bleu","status":"publish","type":"post","link":"https:\/\/alertes-meteo.com\/index.php\/2024\/02\/21\/le-ciel-bleu\/","title":{"rendered":"Le ciel bleu"},"content":{"rendered":"<p>Il est toujours tr\u00e8s instructif d&rsquo;effectuer l&rsquo;observation suivante en montagne: les jours sans vent et sans nuages permettent de voir le bleu du ciel, avec son maximum d&rsquo;intensit\u00e9 et de puret\u00e9, ces derni\u00e8res \u00e9tant plus marqu\u00e9es en hiver qu&rsquo;en \u00e9t\u00e9. Lorsqu&rsquo;on revient dans la vall\u00e9e, le temps peut \u00eatre toujours beau et le soleil peut continuer \u00e0 briller, le bleu du ciel est quand m\u00eame plus p\u00e2le.<br \/>\nEn ville, le ciel est plus souvent d&rsquo;un bleu d\u00e9lav\u00e9 ou d&rsquo;un gris bleut\u00e9 que d&rsquo;un bleu profond. On observe \u00e9galement des diff\u00e9rences de nuances quand on voyage, par exemple en se rendant sous les tropiques. Le ciel du Midi, dans notre h\u00e9misph\u00e8re, n&rsquo;est toutefois pas toujours aussi bleu qu&rsquo;on veut bien le dire.<\/p>\n<p>Le bleu du ciel est le r\u00e9sultat de la diffusion de la lumi\u00e8re solaire par l&rsquo;atmosph\u00e8re. Si celle-ci n&rsquo;existait pas, nous verrions une vo\u00fbte c\u00e9leste toute noire et les \u00e9toiles seraient visibles en plein jour. Les rayons du Soleil sont en effet diffus\u00e9s dans toutes les directions par les mol\u00e9cules de l&rsquo;air, ainsi que par les particules de poussi\u00e8re et par les gouttes d&rsquo;eau de l&rsquo;atmosph\u00e8re.<br \/>\nMais comment peut-on voir cette couleur bleue ? Lorsque nos yeux voient en m\u00eame temps toutes les couleurs du spectre, nous avons la sensation du blanc, le rayonnement bleu de courte longueur d&rsquo;onde \u00e9tant dispers\u00e9 dans l&rsquo;atmosph\u00e8re par les mol\u00e9cules, les poussi\u00e8res et les gouttes d&rsquo;eau. C&rsquo;est donc la partie bleue de la lumi\u00e8re solaire qui se trouve mise de fa\u00e7on pr\u00e9f\u00e9rentielle en \u00e9vidence, \u00e0 l&rsquo;inverse des rayonnements rouge, jaune et vert.<\/p>\n<p>Les variations de tonalit\u00e9 du bleu sont \u00e9galement li\u00e9es \u00e0 la diffusion. Plus il y a de poussi\u00e8res et de gouttes d&rsquo;eau dans l&rsquo;air, plus la couleur bleue est faible. Par temps beau et sec, le ciel parait m\u00eame plus blanc et gris que bleu. A l&rsquo;inverse, l&rsquo;absence de poussi\u00e8res et de gouttes d&rsquo;eau permet \u00e0 la radiation bleue de se renforcer (par exemple en haute montagne).<\/p>\n<p>Le ciel bleu n&rsquo;est pas toujours li\u00e9 \u00e0 l&rsquo;existence de hautes pressions (beau temps). Les \u00e9claircies passag\u00e8res donnent aussi un ciel tr\u00e8s bleu, comme dans le cas du f\u0153hn, vent chaud des Pr\u00e9alpes.<br \/>\nLa visibilit\u00e9 est alors souvent excellente. Il se pr\u00e9sente souvent aussi, avant l&rsquo;arriv\u00e9e d&rsquo;un front chaud faisant suite \u00e0 une perturbation, un d\u00e9gagement subit et de courte dur\u00e9e de la couche de nuages, ce qui donne un ciel tout bleu. Le temps, instable, est alors r\u00e9gi par une basse pression.<br \/>\nL&rsquo;inverse a souvent lieu durant une p\u00e9riode de hautes pressions estivales, pendant laquelle le ciel se d\u00e9colore, du fait de l&rsquo;augmentation des poussi\u00e8res dans l&rsquo;air. La visibilit\u00e9 est alors faible et m\u00eame nettement r\u00e9duite \u00e0 proximit\u00e9 de l&rsquo;horizon.<\/p>\n<p>Il existe \u00e0 ce sujet des diff\u00e9rences saisonni\u00e8res : le bleu du ciel est normalement plus intense pendant les hautes pressions du printemps ou de l&rsquo;automne que pendant celles des mois d&rsquo;\u00e9t\u00e9. M\u00eame lorsqu&rsquo;il y a des hautes pressions, le bleu est affaibli en hiver durant une inversion. L&rsquo;intensit\u00e9 de la couleur bleue s&rsquo;accro\u00eet \u00e9galement en m\u00eame temps que l&rsquo;altitude des lieux d&rsquo;observation.<\/p>\n<p>L&rsquo;intensit\u00e9 de la couleur bleue du ciel peut \u00eatre une indication pour le temps \u00e0 venir. Trois r\u00e8gles fondamentales sont valables \u00e0 ce sujet en plaine :<\/p>\n<ul>\n<li>Le bleu tr\u00e8s fonc\u00e9, li\u00e9 \u00e0 une tr\u00e8s bonne visibilit\u00e9, doit faire penser \u00e0 un temps instable. Une aggravation accompagn\u00e9e de vent (temp\u00eate) et de pr\u00e9cipitations n&rsquo;est pas \u00e0 exclure.<\/li>\n<li>Un bleu moyen ou clair et lumineux fait pr\u00e9sager la persistance du beau temps.<\/li>\n<li>Un passage graduel du bleu au blanc ou au gris, li\u00e9 \u00e0 de la brume, permet de pr\u00e9voir un changement de temps (basse pression).<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Il est toujours tr\u00e8s instructif d&rsquo;effectuer l&rsquo;observation suivante en montagne:  [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":14805,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"none","_seopress_titles_title":"D\u00e9couvrez pourquoi le ciel bleu est plus intense en montagne","_seopress_titles_desc":"Explorez les myst\u00e8res de la couleur du ciel. D\u00e9couvrez les raisons pour lesquelles le ciel bleu varie d&#039;intensit\u00e9 selon le lieu et la saison","_seopress_robots_index":"","_seopress_analysis_target_kw":"ciel bleu,ciel bleu meteo,ciel bleu nuage,ciel bleu pourquoi","footnotes":""},"categories":[132],"tags":[],"class_list":["post-14801","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-phenomenes-meteo"],"_links":{"self":[{"href":"https:\/\/alertes-meteo.com\/index.php\/wp-json\/wp\/v2\/posts\/14801","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alertes-meteo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alertes-meteo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alertes-meteo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/alertes-meteo.com\/index.php\/wp-json\/wp\/v2\/comments?post=14801"}],"version-history":[{"count":0,"href":"https:\/\/alertes-meteo.com\/index.php\/wp-json\/wp\/v2\/posts\/14801\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alertes-meteo.com\/index.php\/wp-json\/wp\/v2\/media\/14805"}],"wp:attachment":[{"href":"https:\/\/alertes-meteo.com\/index.php\/wp-json\/wp\/v2\/media?parent=14801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alertes-meteo.com\/index.php\/wp-json\/wp\/v2\/categories?post=14801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alertes-meteo.com\/index.php\/wp-json\/wp\/v2\/tags?post=14801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}