{"id":14599,"date":"2024-02-19T08:41:22","date_gmt":"2024-02-19T07:41:22","guid":{"rendered":"https:\/\/alertes-meteo.com\/?p=14599"},"modified":"2024-02-19T16:00:11","modified_gmt":"2024-02-19T15:00:11","slug":"la-pression-atmospherique","status":"publish","type":"post","link":"https:\/\/alertes-meteo.com\/index.php\/2024\/02\/19\/la-pression-atmospherique\/","title":{"rendered":"La pression atmosph\u00e9rique"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1302px;margin-left: calc(-5% \/ 2 );margin-right: calc(-5% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:2.375%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:2.375%;--awb-width-medium:100%;--awb-spacing-right-medium:2.375%;--awb-spacing-left-medium:2.375%;--awb-width-small:100%;--awb-spacing-right-small:2.375%;--awb-spacing-left-small:2.375%;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p>Les \u00e9l\u00e9ments m\u00e9t\u00e9orologiques, c&rsquo;est-\u00e0-dire la pression atmosph\u00e9rique, la temp\u00e9rature de l&rsquo;air, l&rsquo;humidit\u00e9 atmosph\u00e9rique, la densit\u00e9 de l&rsquo;air et les vents sont essentiels pour l&rsquo;observation et la pr\u00e9vision du temps. Ils permettent de pr\u00e9voir l&rsquo;essentiel de l&rsquo;\u00e9volution du temps, ce qui suffit largement pour le profane \u00e9clair\u00e9.<\/p>\n<h2 style=\"font-size: 16px;\">La pression atmosph\u00e9rique<\/h2>\n<p>L&rsquo;appareil le plus utilis\u00e9 pour la mesure de la pression atmosph\u00e9rique est le barom\u00e8tre an\u00e9ro\u00efde, constitu\u00e9 par une boite m\u00e9tallique en acier sp\u00e9cial, qui fait office de chambre dans laquelle on a fait le vide. Cette boite s&rsquo;affaisse en fonction de l&rsquo;augmentation de la pression atmosph\u00e9rique, et se gonfle quand celle-ci diminue, aid\u00e9e par l&rsquo;action d&rsquo;un ressort int\u00e9rieur (barom\u00e8tre de Vidi) ; les meilleurs mod\u00e8les sont en r\u00e9alit\u00e9 constitu\u00e9s de plusieurs bo\u00eetes empil\u00e9es. Les mouvements de ce syst\u00e8me sont amplifi\u00e9s et transmis \u00e0 une aiguille, laquelle se d\u00e9place devant un cadran gradu\u00e9 en mm de mercure (mm Hg), en millibars ou, plus rarement, en torrs. Le barom\u00e8tre, quant \u00e0 lui, permet d&rsquo;observer :<\/p>\n<ul>\n<li><span style=\"color: #f9004a;\"><b>l&rsquo;augmentation et la diminution de la pression atmosph\u00e9rique<\/b><\/span><\/li>\n<li><span style=\"color: #f9004a;\"><b>la vitesse (ou mieux la courbe) de l&rsquo;augmentation ou de la diminution de pression.<\/b><\/span><\/li>\n<\/ul>\n<p>C&rsquo;est pourquoi bon nombre de barom\u00e8tres usuels poss\u00e8dent des points de rep\u00e8re, toutefois sans grande signification : beau fixe, beau temps, variable, pluie, temp\u00eate. L&rsquo;aiguille indicatrice est remplac\u00e9e par un stylet encreur dans les mod\u00e8les enregistreurs. Elle inscrit une courbe de variation de la pression sur une feuille gradu\u00e9e en fonction du temps \u00e9coul\u00e9 (chaque feuille couvre une dur\u00e9e d&rsquo;une semaine), entra\u00een\u00e9e par un tambour tournant (un tour en une semaine). Mais les mesures s\u00e9rieuses se font en ayant recours \u00e0 un syst\u00e8me de mesure scientifique, \u00e0 savoir :<\/p>\n<ul>\n<li>en millim\u00e8tres de colonne de mercure,<\/li>\n<li>en torrs,<\/li>\n<li>en millibars (mba) maintenant remplac\u00e9s par les hectopascals (hPa).<\/li>\n<\/ul>\n<p>On trouvera la correspondance de ces unit\u00e9s de mesure dans le tableau ci-dessous. Les barom\u00e8tres \u00e0 colonne de mercure r\u00e9elle sont \u00e0 la fois les plus pr\u00e9cis et les premiers invent\u00e9s. Si l&rsquo;on met \u00e0 part le torr, unit\u00e9 purement scientifique de pression, \u00e9quivalant \u00e0 1\/760 d&rsquo;atmosph\u00e8re, soit 1,333 baries ou 1,333 hPa (mbar), on observe g\u00e9n\u00e9ralement l&rsquo;\u00e9chelle de valeurs suivantes :<\/p>\n<\/div><table border=\"1\" cellspacing=\"0\" width=\"447\">\n  <tr>\n    <td width=\"160\" align=\"center\"><font color=\"#004000\" size=\"2\" face=\"Verdana\"><b>Millim\u00e8tres<\/b><\/font><\/td>\n    <td width=\"163\" align=\"left\"><p style=\"margin-bottom: -1px\" align=\"center\"><font color=\"#004000\" size=\"2\" face=\"Verdana\"><b>Hectopascals<\/b><\/font><\/td>\n    <td width=\"110\" align=\"center\"><font color=\"#004000\" size=\"2\" face=\"Verdana\"><b>\u00a0Pouces anglais<\/b><\/font><\/td>\n  <\/tr>\n  <tr>\n    <td width=\"160\" align=\"center\" height=\"32\"><font color=\"#004000\" size=\"2\" face=\"Arial\">de\n      mercure\u00a0\u00a0\u00a0\u00a0\u00a0<\/font><\/td>\n    <td width=\"163\" align=\"left\" height=\"32\"><p style=\"margin-bottom: -1px\" align=\"center\"><font color=\"#004000\" size=\"2\" face=\"Arial\">(mbar)<\/font><\/td>\n    <td width=\"110\" align=\"center\" height=\"32\"><font color=\"#004000\" size=\"2\" face=\"Arial\">\u00a0\u00a0\n    de mercure<\/font><\/td>\n  <\/tr>\n  <tr>\n    <td width=\"160\" align=\"center\" height=\"16\"><font color=\"#004000\" size=\"2\" face=\"Arial\">720\u00a0<\/font><\/td>\n    <td width=\"163\" align=\"center\" height=\"16\"><p style=\"margin-bottom: -1px\" align=\"center\"><font color=\"#004000\" size=\"2\" face=\"Arial\">960<\/font><\/td>\n    <td width=\"110\" align=\"center\" height=\"16\"><font color=\"#004000\" size=\"2\" face=\"Arial\">28,35<\/font><\/td>\n  <\/tr>\n  <tr>\n    <td width=\"160\" align=\"center\" height=\"16\"><font color=\"#004000\" size=\"2\" face=\"Arial\">724\u00a0<\/font><\/td>\n    <td width=\"163\" align=\"center\" height=\"16\"><p style=\"margin-bottom: -1px\"><font color=\"#004000\" size=\"2\" face=\"Arial\">965<\/font><\/td>\n    <td width=\"110\" align=\"center\" height=\"16\"><font color=\"#004000\" size=\"2\" face=\"Arial\">28,50<\/font><\/td>\n  <\/tr>\n  <tr>\n    <td width=\"160\" align=\"center\" height=\"16\"><font color=\"#004000\" size=\"2\" face=\"Arial\">727,5\u00a0<\/font><\/td>\n    <td width=\"163\" align=\"center\" height=\"16\"><p style=\"margin-bottom: -1px\"><font color=\"#004000\" size=\"2\" face=\"Arial\">970<\/font><\/td>\n    <td width=\"110\" align=\"center\" height=\"16\"><font color=\"#004000\" size=\"2\" face=\"Arial\">28,65<\/font><\/td>\n  <\/tr>\n  <tr>\n    <td width=\"160\" align=\"center\" height=\"16\"><font color=\"#004000\" size=\"2\" face=\"Arial\">731<\/font><\/td>\n    <td width=\"163\" align=\"center\" height=\"16\"><p style=\"margin-bottom: -1px\"><font color=\"#004000\" size=\"2\" face=\"Arial\">975<\/font><\/td>\n    <td width=\"110\" align=\"center\" height=\"16\"><font color=\"#004000\" size=\"2\" face=\"Arial\">28,80<\/font><\/td>\n  <\/tr>\n  <tr>\n    <td width=\"160\" align=\"center\" height=\"16\"><font color=\"#004000\" size=\"2\" face=\"Arial\">735<\/font><\/td>\n    <td width=\"163\" align=\"center\" height=\"16\"><p style=\"margin-bottom: -1px\"><font color=\"#004000\" size=\"2\" face=\"Arial\">980<\/font><\/td>\n    <td width=\"110\" align=\"center\" height=\"16\"><font color=\"#004000\" size=\"2\" face=\"Arial\">28,90<\/font><\/td>\n  <\/tr>\n  <tr>\n    <td width=\"160\" align=\"center\" height=\"16\"><font color=\"#004000\" size=\"2\" face=\"Arial\">739\u00a0<\/font><\/td>\n    <td width=\"163\" align=\"center\" height=\"16\"><p style=\"margin-bottom: -1px\"><font color=\"#004000\" size=\"2\" face=\"Arial\">\u00a0985<\/font><\/td>\n    <td width=\"110\" align=\"center\" height=\"16\"><font color=\"#004000\" size=\"2\" face=\"Arial\">29,10<\/font><\/td>\n  <\/tr>\n  <tr>\n    <td width=\"160\" align=\"center\" height=\"16\"><font color=\"#004000\" size=\"2\" face=\"Arial\">742,5\u00a0<\/font><\/td>\n    <td width=\"163\" align=\"center\" height=\"16\"><p style=\"margin-bottom: -1px\"><font color=\"#004000\" size=\"2\" face=\"Arial\">\u00a0\u00a0990\u00a0\u00a0<\/font><\/td>\n    <td width=\"110\" align=\"center\" height=\"16\"><font color=\"#004000\" size=\"2\" face=\"Arial\">29,25<\/font><\/td>\n  <\/tr>\n  <tr>\n    <td width=\"160\" align=\"center\" height=\"16\"><font color=\"#004000\" size=\"2\" face=\"Arial\">746<\/font><\/td>\n    <td width=\"163\" align=\"center\" height=\"16\"><p style=\"margin-bottom: -1px\" align=\"center\"><font color=\"#004000\" size=\"2\" face=\"Arial\">\u00a0995<\/font><\/td>\n    <td width=\"110\" align=\"center\" height=\"16\"><font color=\"#004000\" size=\"2\" face=\"Arial\">29,40<\/font><\/td>\n  <\/tr>\n  <tr>\n    <td width=\"160\" align=\"center\" height=\"16\"><font color=\"#004000\" size=\"2\" face=\"Arial\">750<\/font><\/td>\n    <td width=\"163\" align=\"center\" height=\"16\"><p style=\"margin-bottom: -1px\"><font color=\"#004000\" size=\"2\" face=\"Arial\">1000<\/font><\/td>\n    <td width=\"110\" align=\"center\" height=\"16\"><font color=\"#004000\" size=\"2\" face=\"Arial\">29,50<\/font><\/td>\n  <\/tr>\n  <tr>\n    <td width=\"160\" align=\"center\" height=\"16\"><font color=\"#004000\" size=\"2\" face=\"Arial\">754\u00a0<\/font><\/td>\n    <td width=\"163\" align=\"center\"><p style=\"margin-bottom: -1px\" align=\"center\"><font color=\"#004000\" size=\"2\" face=\"Arial\">1005<\/font><\/td>\n    <td width=\"110\" align=\"center\" height=\"16\"><font color=\"#004000\" size=\"2\" face=\"Arial\">29,70<\/font><\/td>\n  <\/tr>\n  <tr>\n    <td width=\"160\" align=\"center\" height=\"16\"><font color=\"#004000\" size=\"2\" face=\"Arial\">757,5\u00a0<\/font><\/td>\n\n  <\/center>\n    <td width=\"163\" align=\"center\" height=\"16\"><p style=\"margin-bottom: -1px\" align=\"center\"><font color=\"#004000\" size=\"2\" face=\"Arial\">1010<\/font><\/td>\n  <center>\n\n    <td width=\"110\" align=\"center\" height=\"16\"><font color=\"#004000\" size=\"2\" face=\"Arial\">29,80<\/font><\/td>\n  <\/tr>\n  <tr>\n    <td width=\"160\" align=\"center\" height=\"16\"><font color=\"#004000\">761<\/font><\/td>\n    <td width=\"163\" align=\"center\" height=\"16\"><p style=\"margin-bottom: -1px\"><font color=\"#004000\">1015<\/font><\/td>\n    <td width=\"110\" align=\"center\" height=\"16\"><font color=\"#004000\">\n    30<\/font><\/td>\n  <\/tr>\n  <tr>\n    <td width=\"160\" align=\"center\" height=\"16\"><font color=\"#004000\" size=\"2\" face=\"Arial\">765<\/font><\/td>\n    <td width=\"163\" align=\"center\" height=\"16\"><p style=\"margin-bottom: -1px\"><font color=\"#004000\" size=\"2\" face=\"Arial\">1020<\/font><\/td>\n    <td width=\"110\" align=\"center\" height=\"16\"><font color=\"#004000\" size=\"2\" face=\"Arial\">30,10<\/font><\/td>\n  <\/tr>\n  <tr>\n    <td width=\"160\" align=\"center\" height=\"16\"><font color=\"#004000\" size=\"2\" face=\"Arial\">769<\/font><\/td>\n    <td width=\"163\" align=\"center\" height=\"16\"><p style=\"margin-bottom: -1px\"><font color=\"#004000\" size=\"2\" face=\"Arial\">1025<\/font><\/td>\n    <td width=\"110\" align=\"center\" height=\"16\"><font color=\"#004000\" size=\"2\" face=\"Arial\">30,30<\/font><\/td>\n  <\/tr>\n  <tr>\n    <td width=\"160\" align=\"center\" height=\"16\"><font color=\"#004000\" size=\"2\" face=\"Arial\">772,5\u00a0<\/font><\/td>\n    <td width=\"163\" align=\"center\" height=\"16\"><p style=\"margin-bottom: -1px\"><font color=\"#004000\" size=\"2\" face=\"Arial\">1030<\/font><\/td>\n    <td width=\"110\" align=\"center\" height=\"16\"><font color=\"#004000\" size=\"2\" face=\"Arial\">30,40<\/font><\/td>\n  <\/tr>\n  <tr>\n    <td width=\"160\" align=\"center\" height=\"16\"><font color=\"#004000\" size=\"2\" face=\"Arial\">776<\/font><\/td>\n    <td width=\"163\" align=\"center\" height=\"16\"><p style=\"margin-bottom: -1px\"><font color=\"#004000\" size=\"2\" face=\"Arial\">1035<\/font><\/td>\n    <td width=\"110\" align=\"center\" height=\"16\"><font color=\"#004000\" size=\"2\" face=\"Arial\">\n    30,55<\/font><\/td>\n  <\/tr>\n  <tr>\n    <td width=\"160\" align=\"center\" height=\"16\"><font color=\"#004000\" size=\"2\" face=\"Arial\">780<\/font><\/td>\n    <td width=\"163\" align=\"center\" height=\"16\"><p style=\"margin-bottom: -1px\"><font color=\"#004000\" size=\"2\" face=\"Arial\">1040<\/font><\/td>\n    <td width=\"110\" align=\"center\" height=\"16\"><font color=\"#004000\" size=\"2\" face=\"Arial\">30,70<\/font><\/td>\n  <\/tr>\n<\/table><div class=\"fusion-text fusion-text-2\"><p>On peut, dans la pratique, afin de convertir les mm de mercure (mm Hg) en millibars, et r\u00e9ciproquement, adopter la correspondance math\u00e9matique suivante :<\/p>\n<ul>\n<li>1 mm Hg = 1,333 hPa (mbar)<\/li>\n<li>1 hPa = 0,750 mm Hg<\/li>\n<\/ul>\n<p>Une m\u00e9thode simple permet de suivre les variations de la pression atmosph\u00e9rique : on reporte sur du papier millim\u00e9tr\u00e9 les valeurs lues sur le barom\u00e8tre, \u00e0 raison de 5 mm par jour en abscisses (horizontalement) et de 1 mm par mm Hg ou par mbar, au besoin en portant la correspondance entre ces deux unit\u00e9s (760 mm Hg = 1 0 13 hPa en valeur approch\u00e9e). Il convient de lire le barom\u00e8tre chaque jour \u00e0 la m\u00eame heure et il est bon de noter \u00e0 ce moment l&rsquo;\u00e9tat du temps. Au bout de plusieurs mois, on arrivera ainsi \u00e0 avoir une bonne exp\u00e9rience de la correspondance entre, la pression atmosph\u00e9rique et le temps. En outre, un observateur attentif constatera vite que les hautes pressions ne sont pas toujours le signe de beau temps, et r\u00e9ciproquement.<\/p>\n<div>\n<p><span style=\"background-color: var(--awb-bg-color-small-hover); color: var(--awb-text-color); font-family: var(--awb-text-font-family); font-size: var(--awb-font-size); font-style: var(--awb-text-font-style); font-weight: var(--awb-text-font-weight); letter-spacing: var(--awb-letter-spacing); text-align: var(--awb-content-alignment); text-transform: var(--awb-text-transform);\">L&#8217;emploi du barom\u00e8tre enregistreur ou barographe, dont nous avons parl\u00e9, plus haut, est bien s\u00fbr plus rationnel que le report, toujours incomplet, sur papier millim\u00e9tr\u00e9. Naturellement, le barom\u00e8tre enregistreur doit \u00eatre, pour donner des indications pr\u00e9cises, install\u00e9 de fa\u00e7on stable \u00e0 l&rsquo;abri des tr\u00e9pidations et des secousses quelconques.<\/span><\/p>\n<div>\n<p><span style=\"color: var(--awb-text-color); font-family: var(--awb-text-font-family); font-size: var(--awb-font-size); font-style: var(--awb-text-font-style); font-weight: var(--awb-text-font-weight); letter-spacing: var(--awb-letter-spacing); text-align: var(--awb-content-alignment); text-transform: var(--awb-text-transform); background-color: var(--awb-bg-color-small-hover);\">On peut enfin, faute de mieux, employer un altim\u00e8tre pour mesurer la pression atmosph\u00e9rique. Les appareils portables de ce genre ne sont que des barom\u00e8tres an\u00e9ro\u00efdes, gradu\u00e9s g\u00e9n\u00e9ralement en mm Hg ou en millibars ainsi qu&rsquo;en m\u00e8tres d&rsquo;altitude : ils servent aux alpinistes, aussi bien pour la connaissance de l&rsquo;altitude atteinte que pour l&rsquo;observation des changements de pression atmosph\u00e9rique, donc des changements de temps. Il existe enfin pour les laboratoires des barom\u00e8tres \u00e0 colonne de mercure de haute pr\u00e9cision : un flotteur, situ\u00e9 \u00e0 la surface du mercure de la cuvette de l&rsquo;appareil, transmet, par l&rsquo;interm\u00e9diaire d&rsquo;un syst\u00e8me de leviers, les fluctuations de cette surface, donc de la pression atmosph\u00e9rique, \u00e0 une aiguille indicatrice (sur un cadran gradu\u00e9) ou \u00e0 un stylet encreur d&rsquo;enregistreur (sur bande et tambour).<\/span><\/p>\n<div>\n<p>&nbsp;<\/p>\n<h3>PRESSION BAROM\u00c9TRIQUE ABSOLUE<\/h3>\n<p>Valeur r\u00e9elle et absolue (par rapport \u00e0 la valeur \u00a0\u00bb au niveau de la mer \u00ab\u00a0) de la pression atmosph\u00e9rique en un lieu donn\u00e9. Cette valeur est importante pour la pr\u00e9vision du temps, du fait qu&rsquo;elle est comparable avec les mesures effectu\u00e9es en d&rsquo;autres lieux, apr\u00e8s r\u00e9duction en fonction de la valeur au niveau de la mer.<\/p>\n<p><b>PRESSION BAROM\u00c9TRIQUE MOYENNE OU RELATIVE <\/b><\/p>\n<p>Valeur moyenne en fonction de l&rsquo;altitude, qui produit une diminution de la pression atmosph\u00e9rique dite \u00a0\u00bb normale \u00ab\u00a0. Elle est de 760 mm Hg (1 0 13 hPa) \u00e0 0 m d&rsquo;altitude, de 716 mm Hg \u00e0 500 m d&rsquo;altitude (954,5 hPa) et de 674 mm Hg \u00e0 1 000 m d&rsquo;altitude (899 hPa), etc. Aux altitudes inf\u00e9rieures, la diminution de pression est en gros de 1 hPa tous les 8 m\u00e8tres d&rsquo;altitude.<\/p>\n<p><b>PRESSION BAROM\u00c9TRIQUE R\u00c9DUITE AU NIVEAU DE LA MER <\/b><\/p>\n<p>Cette pression, dite normale, sert \u00e0 la mesure comparative de la pression des stations d&rsquo;altitude plus \u00e9lev\u00e9e que le niveau de la mer. On consid\u00e8re que, dans&rsquo; les conditions normales, \u00e0 l&rsquo;altitude de 0 m\u00e8tre (niveau de la mer), la pression atmosph\u00e9rique est de 760 mm de mercure, soit 1 0 13 hPa. Pour \u00e9talonner son propre barom\u00e8tre par r\u00e9duction \u00e0 la normale (en fonction de l&rsquo;altitude du lieu. d&#8217;emploi), on se renseignera aupr\u00e8s des services m\u00e9t\u00e9orologiques locaux ou on fera la correction n\u00e9cessaire d&rsquo;apr\u00e8s l&rsquo;indication de l&rsquo;altitude sur la carte d&rsquo;\u00e9tat-major. Mais le mieux est d&rsquo;utiliser un barom\u00e8tre de bonne qualit\u00e9, qui comporte une correction par rotation du cadran (ou par r\u00e9glage du syst\u00e8me de leviers dans les mod\u00e8les enregistreurs) en fonction de l&rsquo;altitude sur la carte. On ne s&rsquo;\u00e9tonnera donc pas d&rsquo;entendre, dans les stations radiophoniques locales, des informations de ce type : \u00a0\u00bb pression atmosph\u00e9rique, r\u00e9duite au niveau de la mer: 765 mm ou 1 020 hPa \u00ab\u00a0.<\/p>\n<p>L&rsquo;\u00e9volution de la pression atmosph\u00e9rique est d&rsquo;abord quotidienne : elle tend \u00e0 augmenter le matin et pendant la nuit. Elle baisse l&rsquo;apr\u00e8s-midi par suite du r\u00e9chauffement diurne, surtout en \u00e9t\u00e9. Ces variations journali\u00e8res repr\u00e9sentent en moyenne, 1 mbar, ind\u00e9pendamment de J&rsquo;\u00e9volution du temps ; elles ressemblent quelque peu aux mar\u00e9es et sont dues elles aussi \u00e0 la Position r\u00e9ciproque du Soleil et de la Lune. Ces variations quotidiennes sont faciles \u00e0 observer par temps constant. En montagne, on observe le ph\u00e9nom\u00e8ne inverse : la tendance est \u00e0 l&rsquo;augmentation dans l&rsquo;apr\u00e8s-midi lorsque l&rsquo;air affluant provoque une suppression.<\/p>\n<p>Il se produit aussi des variations saisonni\u00e8res. Ainsi, on observe une tendance \u00e0 l&rsquo;\u00e9l\u00e9vation de la pression d&rsquo;ao\u00fbt \u00e0 septembre, et \u00e0 la diminution de la pression par la suite, surtout en avril. En montagne, on observe les plus hautes pressions en \u00e9t\u00e9 et les Plus basses en hiver. Ces observations sont bien s\u00fbr conditionn\u00e9es par l&rsquo;\u00e9volution du temps : il y a peu de basses pressions en automne, et beaucoup au printemps, ce qui influe nettement sur le temps dans les deux cas. Les basses pressions d&rsquo;hiver jouent un grand r\u00f4le pendant l&rsquo;hiver en montagne.<br \/>\nEn r\u00e9alit\u00e9, le barom\u00e8tre traduit en un lieu donn\u00e9 l&rsquo;\u00e9tat de la colonne d&rsquo;air qui le surmonte. L&rsquo;air froid est dense et fait \u00a0\u00bb monter \u00a0\u00bb le barom\u00e8tre : on observe une haute pression. L&rsquo;air chaud est l\u00e9ger : on observe une basse pression. La vitesse de l&rsquo;\u00e9volution de la pression atmosph\u00e9rique est tr\u00e8s utile pour la pr\u00e9vision du temps \u00e0 venir.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div><table border=\"1\" cellspacing=\"0\" width=\"94%\" bordercolorlight=\"#FFFFFF\" bordercolordark=\"#000000\">\n  <tr>\n    <td width=\"26%\" align=\"center\" bgcolor=\"#F0F0F0\"><strong><font face=\"Verdana\" size=\"2\"><font color=\"#004040\">Tendance\n    du <\/font>barom\u00e8tre<\/font><\/strong><\/td>\n    <td width=\"17%\" align=\"center\" bgcolor=\"#F0F0F0\"><strong><font color=\"#004040\" face=\"Verdana\" size=\"2\">hPa\n    par heure<\/font><\/strong><\/td>\n    <td width=\"57%\" align=\"center\" bgcolor=\"#F0F0F0\"><strong><font size=\"2\" color=\"#004040\" face=\"Verdana\">\u00c9volution\n    du temps<\/font><\/strong><\/td>\n  <\/tr>\n  <tr>\n    <td width=\"26%\" align=\"center\" bgcolor=\"#F0F0F0\"><font face=\"Verdana\" size=\"2\">mont\u00e9e<\/font><\/td>\n    <td width=\"17%\" align=\"center\" bgcolor=\"#F0F0F0\"><font face=\"Verdana\" size=\"2\">0,25 \u00e0 0,5<\/font><\/td>\n    <td width=\"57%\" align=\"center\" bgcolor=\"#F0F0F0\"><font face=\"Verdana\" size=\"2\">venue d'une haute pression(\u00e0 long\n    terme)<\/font><\/td>\n  <\/tr>\n  <tr>\n    <td width=\"26%\" align=\"center\" bgcolor=\"#F0F0F0\"><font face=\"Verdana\" size=\"2\">mont\u00e9e<\/font><\/td>\n    <td width=\"17%\" align=\"center\" bgcolor=\"#F0F0F0\"><font face=\"Verdana\" size=\"2\">1 \u00e0 2<\/font><\/td>\n    <td width=\"57%\" align=\"center\" bgcolor=\"#F0F0F0\"><font face=\"Verdana\" size=\"2\">moyenne pression (\u00e0 court terme)<\/font><\/td>\n  <\/tr>\n  <tr>\n    <td width=\"26%\" align=\"center\" bgcolor=\"#F0F0F0\"><font face=\"Verdana\" size=\"2\">descente<\/font><\/td>\n    <td width=\"17%\" align=\"center\" bgcolor=\"#F0F0F0\"><font face=\"Verdana\" size=\"2\">0,25 \u00e0 0,5<\/font><\/td>\n    <td width=\"57%\" align=\"center\" bgcolor=\"#F0F0F0\"><font face=\"Verdana\" size=\"2\">venue d'une basse pression(\u00e0 long\n    terme)<\/font><\/td>\n  <\/tr>\n  <tr>\n    <td width=\"26%\" align=\"center\" bgcolor=\"#F0F0F0\"><font face=\"Verdana\" size=\"2\">descente<\/font><\/td>\n    <td width=\"17%\" align=\"center\" bgcolor=\"#F0F0F0\"><font face=\"Verdana\" size=\"2\">1 \u00e0 2<\/font><\/td>\n    <td width=\"57%\" align=\"center\" bgcolor=\"#F0F0F0\"><font face=\"Verdana\" size=\"2\">temp\u00eate ; en \u00e9t\u00e9, orage.<\/font><\/td>\n  <\/tr>\n<\/table>\n<div class=\"fusion-text fusion-text-3\"><p>&nbsp;<\/p>\n<p>Il y a bien des exceptions \u00e0 ce sch\u00e9ma g\u00e9n\u00e9ral. Nous en donnerons quelques exemples.<br \/>\nLorsque le barom\u00e8tre a tendance \u00e0 baisser au lieu d&rsquo;observation, le temps est quand m\u00eame beau. De l&rsquo;air chaud venant du sud descend au soi vers le nord. On observe une baisse de la pression atm6sph\u00e9rique. L&rsquo;air chaud \u00e0 proximit\u00e9 du soi progresse tr\u00e8s vite (plus vite qu&rsquo;en altitude) et de l&rsquo;air froid arrive \u00e0 l&rsquo;arri\u00e8re, en provenance des hautes altitudes. Cet air descendant dirige les nuages et d\u00e9gage le Soleil. Lorsque le barom\u00e8tre a tendance \u00e0 augmenter au lieu d&rsquo;observation : le temps est quand m\u00eame nuageux et pluvieux. De l&rsquo;air froid proche du sol et venant du nord souffle rapidement au sud. On observe une \u00e9l\u00e9vation de la pression atmosph\u00e9rique. L&rsquo;air froid repousse l&rsquo;air chaud stationnaire en altitude. Mais le refroidissement a les cons\u00e9quences suivantes pour l&rsquo;air chaud : des nuages se forment et des pr\u00e9cipitations ont lieu. Apr\u00e8s le passage d&rsquo;une zone de basse pression, des coins de haute pression provoquent souvent de rapides augmentations de la pression atmosph\u00e9rique. Malgr\u00e9 le vent fort, il pleut ou il neige ensuite. L&rsquo;air froid fait s&rsquo;\u00e9lever l&rsquo;air chaud et en provoque le refroidissement. Finalement, au cours de l&rsquo;\u00e9volution d&rsquo;une situation de haute pression de longue dur\u00e9e, on observe une nouvelle augmentation de la pression atmosph\u00e9rique. En m\u00eame temps, le Soleil est masqu\u00e9 et le ciel devient brumeux (voir <a href=\"https:\/\/alertes-meteo.com\/index.php\/2024\/02\/13\/la-brume\/\">brume <\/a>).<br \/>\nOn repr\u00e9sente la situation du point de vue de la pression atmosph\u00e9rique par des \u00a0\u00bb isobares \u00a0\u00bb sur les cartes du temps. De plus, tous les lieux o\u00f9 la pression est la m\u00eame sont reli\u00e9s par les lignes. Les isobares sont habituellement trac\u00e9es pour des interlignes de 5 en 5 millibars en ramenant naturellement les mesures au niveau de la mer. Dispos\u00e9es en cercles, les isobares d\u00e9limitent des anticyclones (la pression augmente vers le centre) et des d\u00e9pressions (la pression diminue vers le centre). Il est particuli\u00e8rement int\u00e9ressant d&rsquo;observer les intervalles entre les isobares successives, d&rsquo;autant plus grands que la diminution est plus faible.<\/p>\n<\/div><table border=\"1\" cellspacing=\"0\" width=\"90%\" bordercolorlight=\"#FFFFFF\" bordercolordark=\"#000000\" bgcolor=\"#F0F0F0\">\n  <tr>\n    <font size=\"3\"><td width=\"29%\" align=\"center\"><\/font><strong><font size=\"2\" color=\"#004040\" face=\"Verdana\">Intervalles entre les isobares<\/font><\/strong><\/td>\n    <td width=\"32%\" align=\"center\"><font color=\"#004040\" face=\"Verdana\" size=\"2\"><strong>Diff\u00e9rence de\n    pression<\/strong><\/font><\/td>\n    <td width=\"39%\" align=\"center\"><strong><font size=\"2\" color=\"#004040\" face=\"Verdana\">\u00c9volution\n    du temps<\/font><\/strong><\/td>\n  <\/tr>\n  <tr>\n    <td width=\"29%\" align=\"center\"><font color=\"#004040\" face=\"Verdana\" size=\"2\">faible<\/font><\/td>\n    <td width=\"32%\" align=\"center\"><font color=\"#004040\" face=\"Verdana\" size=\"2\">importante<\/font><\/td>\n    <td width=\"39%\" align=\"center\"><font color=\"#004040\" face=\"Verdana\" size=\"2\">turbulences (temp\u00eate)<\/font><\/td>\n  <\/tr>\n  <tr>\n    <td width=\"29%\" align=\"center\"><font color=\"#004040\" face=\"Verdana\" size=\"2\">importante<\/font><\/td>\n    <td width=\"32%\" align=\"center\"><font color=\"#004040\" face=\"Verdana\" size=\"2\">faible<\/font><\/td>\n    <td width=\"39%\" align=\"center\"><font color=\"#004040\" face=\"Verdana\" size=\"2\">calme (vent faible)<\/font><\/td>\n  <\/tr>\n<\/table>\n\n  <\/center>\n<div class=\"fusion-text fusion-text-4\"><p>&nbsp;<\/p>\n<p>On peut de la sorte trouver, la diff\u00e9rence de pression ou \u00a0\u00bb gradient \u00ab\u00a0. Il s&rsquo;agit de la baisse de pression en hectopascals (millibars) sur une distance de 60 milles marins, \u00e0 la verticale des isobares. Par exemple, l&rsquo;intervalle entre une isobare de 1 005 hPa et une de 1 010 hPa donne un gradient de 6 hPa, pour 60 milles marins selon ce calcul :<\/p>\n<\/div><div class=\"fusion-image-element \" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none\"><img decoding=\"async\" width=\"772\" height=\"46\" title=\"2024-02-19_13h24_25\" src=\"https:\/\/alertes-meteo.com\/wp-content\/uploads\/2024\/02\/2024-02-19_13h24_25.jpg\" data-orig-src=\"https:\/\/alertes-meteo.com\/wp-content\/uploads\/2024\/02\/2024-02-19_13h24_25.jpg\" alt class=\"lazyload img-responsive wp-image-14615\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27772%27%20height%3D%2746%27%20viewBox%3D%270%200%20772%2046%27%3E%3Crect%20width%3D%27772%27%20height%3D%2746%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/alertes-meteo.com\/wp-content\/uploads\/2024\/02\/2024-02-19_13h24_25-200x12.jpg 200w, https:\/\/alertes-meteo.com\/wp-content\/uploads\/2024\/02\/2024-02-19_13h24_25-400x24.jpg 400w, https:\/\/alertes-meteo.com\/wp-content\/uploads\/2024\/02\/2024-02-19_13h24_25-600x36.jpg 600w, https:\/\/alertes-meteo.com\/wp-content\/uploads\/2024\/02\/2024-02-19_13h24_25.jpg 772w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 800px) 100vw, 772px\" \/><\/span><\/div><div class=\"fusion-text fusion-text-5\"><p>La rotation de la Terre a la plus grande importance pour la direction des vents, dans le cas des grands courants atmosph\u00e9riques. Ceux-ci sont d\u00e9vi\u00e9s par la \u00a0\u00bb force de Coriolis \u00ab\u00a0.<\/p>\n<h4>La temp\u00e9rature atmosph\u00e9rique<\/h4>\n<p>Les thermom\u00e8tres du commerce sont des appareils \u00e0 colonne d&rsquo;alcool ou de mercure ou bien encore \u00e0 bilame ou \u00e0 couple thermo\u00e9lectrique. Ces deux derniers mod\u00e8les ont pour avantage de poss\u00e9der une vis de r\u00e9glage partiel. Les thermom\u00e8tres \u00e0 liquide sont fond\u00e9s sur le principe de la dilatation d&rsquo;un liquide lors d&rsquo;un \u00e9chauffement et de sa r\u00e9traction lors d&rsquo;un refroidissement, qu&rsquo;il s&rsquo;agisse d&rsquo;alcool color\u00e9 ou de mercure. Les appareils \u00e0 couple thermo\u00e9lectrique poss\u00e8dent deux bandes m\u00e9talliques de nature diff\u00e9rente et assembl\u00e9es par deux soudures, celles-ci engendrent un courant quand elles sont \u00e9chauff\u00e9es. Les thermom\u00e8tres \u00e0 bilame sont constitu\u00e9s par deux bandes courbes de m\u00e9tal, dont la dilatation \u00e0 la chaleur est diff\u00e9rente. Enfin, il existe des thermom\u00e8tres enregistreurs, \u00e9tablis selon le principe des barom\u00e8tres enregistreurs dont nous parlons plus haut : le syst\u00e8me actif est soit un thermom\u00e8tre \u00e0 bilame, soit un thermom\u00e8tre \u00e0 liquide sp\u00e9cial (form\u00e9 par une bo\u00eete m\u00e9tallique r\u00e9formable sous l&rsquo;action de la temp\u00e9rature, remplie de p\u00e9trole) ; les d\u00e9placements correspondant aux diff\u00e9rentes temp\u00e9ratures sont amplifi\u00e9s et transmis par un jeu de levier et inscrits par un stylet encreur sur une bande de papier que porte un tambour tournant. Il existe par ailleurs des thermom\u00e8tres \u00e0 maxima et minima, qui permettent de mesurer (sans obligation de permanence de l&rsquo;observateur) la plus haute et la plus basse temp\u00e9rature (le maximum et le minimum) pour une p\u00e9riode donn\u00e9e (g\u00e9n\u00e9ralement une journ\u00e9e enti\u00e8re, ou une demi-journ\u00e9e, le plus souvent une nuit). Il s&rsquo;agit d&rsquo;appareils \u00e0 mercure et \u00e0 alcool, qui marquent le maximum et le minimum de temp\u00e9rature enregistr\u00e9e au moyen de petits index.<br \/>\nLes thermom\u00e8tres sont gradu\u00e9s en fonction du point de cong\u00e9lation et du point d&rsquo;\u00e9bullition de l&rsquo;eau pure (100 \u00b0C). \u00c9chelles thermom\u00e9trique est obtenue en divisant l&rsquo;intervalle entre les deux points d\u00e9termin\u00e9s sur une colonne de liquide en 100 espaces \u00e9gaux. Cette \u00e9chelle, dite aussi cent\u00e9simale, fut invent\u00e9e par l&rsquo;astronome su\u00e9dois Anders Celsius (1701 &#8211; 1744). L&rsquo;\u00e9chelle de Fahrenheit, invent\u00e9e par le physicien prussien Gabriel Fahrenheit (1686-1736) et encore employ\u00e9e par les Anglo-Saxons malgr\u00e9 la r\u00e9forme m\u00e9trique, se r\u00e9f\u00e8re aux m\u00eames points extr\u00eames, tout en \u00e9tant divis\u00e9e en 180\u00b0. Nous citerons pour m\u00e9moire l&rsquo;\u00e9chelle de R\u00e9aumur (1683-1757), biologiste fran\u00e7ais, qui comptait 80 degr\u00e9s. On trouvera ci-dessous le tableau comparatif des temp\u00e9ratures dans les trois syst\u00e8mes.<\/p>\n<p><b>Tableau comparatif des \u00e9chelles thermom\u00e9triques<\/b><\/p>\n<\/div><table border=\"1\" width=\"98%\" cellspacing=\"0\" cellpadding=\"0\" bordercolorlight=\"#000000\" bordercolordark=\"#FFFFFF\" bgcolor=\"#F0F0F0\">\n  <tr>\n    <td width=\"26%\" align=\"center\"><\/font><strong><font color=\"#000040\" face=\"Verdana\" size=\"2\">Celsius<\/font><\/strong><\/td>\n    <td width=\"40%\" align=\"center\"><strong><font color=\"#000040\" face=\"Verdana\" size=\"2\">Fahrenheit<\/font><\/strong><\/td>\n    <td width=\"34%\" align=\"center\"><strong><font color=\"#000040\" size=\"2\" face=\"Verdana\">R\u00e9aumur<\/font><\/strong><\/td>\n  <\/tr>\n  <tr>\n    <td width=\"26%\" align=\"center\"><font face=\"Verdana\" size=\"2\">- 25\u00b0<\/font><\/td>\n    <td width=\"40%\" align=\"center\"><font face=\"Verdana\" size=\"2\">- 13\u00b0<\/font><\/td>\n    <td width=\"34%\" align=\"center\"><font face=\"Verdana\" size=\"2\">- 20\u00b0<\/font><\/td>\n  <\/tr>\n  <tr>\n    <td width=\"26%\" align=\"center\"><font face=\"Verdana\" size=\"2\">- 15\u00b0<\/font><\/td>\n    <td width=\"40%\" align=\"center\"><font face=\"Verdana\" size=\"2\">+ 5\u00b0<\/font><\/td>\n    <td width=\"34%\" align=\"center\"><font face=\"Verdana\" size=\"2\">- 12\u00b0<\/font><\/td>\n  <\/tr>\n  <tr>\n    <td width=\"26%\" align=\"center\"><font face=\"Verdana\" size=\"2\">- 5\u00b0<\/font><\/td>\n    <td width=\"40%\" align=\"center\"><font face=\"Verdana\" size=\"2\">+ 23\u00b0<\/font><\/td>\n    <td width=\"34%\" align=\"center\"><font face=\"Verdana\" size=\"2\">4\u00b0<\/font><\/td>\n  <\/tr>\n  <tr>\n    <td width=\"26%\" align=\"center\"><font face=\"Verdana\" size=\"2\">0\u00b0<\/font><\/td>\n    <td width=\"40%\" align=\"center\"><font face=\"Verdana\" size=\"2\">+ 32\u00b0<\/font><\/td>\n    <td width=\"34%\" align=\"center\"><font face=\"Verdana\" size=\"2\">0\u00b0<\/font><\/td>\n  <\/tr>\n  <tr>\n    <td width=\"26%\" align=\"center\"><font face=\"Verdana\" size=\"2\">+ 5\u00b0<\/font><\/td>\n    <td width=\"40%\" align=\"center\"><font face=\"Verdana\" size=\"2\">+ 41\u00b0<\/font><\/td>\n    <td width=\"34%\" align=\"center\"><font face=\"Verdana\" size=\"2\">+ 4\u00b0<\/font><\/td>\n  <\/tr>\n  <tr>\n    <td width=\"26%\" align=\"center\"><font face=\"Verdana\" size=\"2\">+ 10\u00b0<\/font><\/td>\n    <td width=\"40%\" align=\"center\"><font face=\"Verdana\" size=\"2\">+ 50\u00b0<\/font><\/td>\n    <td width=\"34%\" align=\"center\"><font face=\"Verdana\" size=\"2\">+ 8\u00b0<\/font><\/td>\n  <\/tr>\n  <tr>\n    <td width=\"26%\" align=\"center\"><font face=\"Verdana\" size=\"2\">+ 15\u00b0<\/font><\/td>\n    <td width=\"40%\" align=\"center\"><font face=\"Verdana\" size=\"2\">+ 59 \u00b0<\/font><\/td>\n    <td width=\"34%\" align=\"center\"><font face=\"Verdana\" size=\"2\">+ 12\u00b0<\/font><\/td>\n  <\/tr>\n  <tr>\n    <td width=\"26%\" align=\"center\"><font face=\"Verdana\" size=\"2\">+ 20\u00b0<\/font><\/td>\n    <td width=\"40%\" align=\"center\"><font face=\"Verdana\" size=\"2\">+ 68 \u00b0<\/font><\/td>\n    <td width=\"34%\" align=\"center\"><font face=\"Verdana\" size=\"2\">+ 16\u00b0<\/font><\/td>\n  <\/tr>\n  <tr>\n    <td width=\"26%\" align=\"center\"><font face=\"Verdana\" size=\"2\">+ 25\u00b0<\/font><\/td>\n    <td width=\"40%\" align=\"center\"><font face=\"Verdana\" size=\"2\">+ 77\u00b0<\/font><\/td>\n    <td width=\"34%\" align=\"center\"><font face=\"Verdana\" size=\"2\">+ 20\u00b0<\/font><\/td>\n  <\/tr>\n<\/table>\n\n<div class=\"fusion-text fusion-text-6\"><p>Points fixes de ces \u00e9chelles :<\/p>\n<\/div><table border=\"1\" width=\"98%\" cellspacing=\"0\" cellpadding=\"0\" bordercolordark=\"#FFFFFF\" bordercolorlight=\"#000000\" bgcolor=\"#F0F0F0\">\n  <tr>\n    <td width=\"28%\"><font face=\"Verdana\" size=\"2\">\u00a0<\/font><\/td>\n    <td width=\"29%\" align=\"center\"><font face=\"Verdana\" size=\"2\"><b>Celsius<\/b><\/font><\/td>\n    <td width=\"18%\" align=\"center\"><font face=\"Verdana\" size=\"2\"><b>Fahrenheit<\/b><\/font><\/td>\n    <td width=\"25%\" align=\"center\"><font face=\"Verdana\" size=\"2\"><b>R\u00e9aumur<\/b><\/font><\/td>\n  <\/tr>\n  <tr>\n    <td width=\"28%\">\n      <p style=\"margin-left: 2\"><b><font face=\"Verdana\" size=\"1\">Point de cong\u00e9lation de l'eau pure<\/font><\/b><\/p>\n    <\/td>\n    <td width=\"29%\" align=\"center\"><font face=\"Verdana\" size=\"2\">0\u00b0<\/font><\/td>\n    <td width=\"18%\" align=\"center\"><font face=\"Verdana\" size=\"2\">+ 32\u00b0<\/font><\/td>\n    <td width=\"25%\" align=\"center\"><font face=\"Verdana\" size=\"2\">0\u00b0<\/font><\/td>\n  <\/tr>\n  <tr>\n    <td width=\"28%\">\n      <p style=\"margin-left: 2\"><b><font face=\"Verdana\" size=\"1\">Point d'ebullition de l'eau pure<\/font><\/b><\/p>\n    <\/td>\n    <td width=\"29%\" align=\"center\"><font face=\"Verdana\" size=\"2\">+ 100\u00b0<\/font><\/td>\n    <td width=\"18%\" align=\"center\"><font face=\"Verdana\" size=\"2\">+ 212\u00b0<\/font><\/td>\n    <td width=\"25%\" align=\"center\"><font face=\"Verdana\" size=\"2\">+ 80\u00b0<\/font><\/td>\n  <\/tr>\n<\/table>\n<div class=\"fusion-text fusion-text-7\"><p>&nbsp;<\/p>\n<p><span style=\"color: var(--awb-text-color); font-family: var(--awb-text-font-family); font-size: var(--awb-font-size); font-style: var(--awb-text-font-style); font-weight: var(--awb-text-font-weight); letter-spacing: var(--awb-letter-spacing); text-align: var(--awb-content-alignment); text-transform: var(--awb-text-transform); background-color: var(--awb-bg-color-hover);\">Pour Contr\u00f4ler si un thermom\u00e8tre est juste, on emplit un verre de glace et on y plonge aussi profond\u00e9ment que possible l&rsquo;instrument \u00e0 v\u00e9rifier La temp\u00e9rature indiqu\u00e9e par le thermom\u00e8tre doit \u00eatre celle de la glace fondante, soit 0\u00b0C. Puis on plonge le thermom\u00e8tre dans de l&rsquo;eau \u00e0 35\u00b0C en comparant son indication avec un thermom\u00e8tre m\u00e9dical, assez pr\u00e9cis : les graduations doivent concorder.<\/span><\/p>\n<p>La temp\u00e9rature de l&rsquo;air, \u00e0 condition que le thermom\u00e8tre utilis\u00e9 soit bien exact, doit \u00eatre mesur\u00e9e en un lieu bien a\u00e9r\u00e9 et \u00e0 l&rsquo;abri des rayons solaires : la proximit\u00e9 d&rsquo;une fen\u00eatre ou d&rsquo;une maison fausserait par exemple les mesures. Dans les stations m\u00e9t\u00e9orologiques (l&rsquo;amateur peut s&rsquo;en fabriquer une \u00e0 peu de frais), le thermom\u00e8tre est plac\u00e9, avec tous les autres instruments, dans un abri en bois peint o\u00f9 l&rsquo;air peut circuler librement, \u00e0 deux m\u00e8tres au-dessus du soi.<br \/>\nEn ce qui concerne la temp\u00e9rature journali\u00e8re, on observe que les diff\u00e9rences sont plus importantes sur la terre ferme qu&rsquo;en mer. Dans les deux cas, il y a un minimum peu avant le lever du Soleil, et un maximum \u00e0 14 heures (heure solaire). Mais, quand le r\u00e9chauffement et le rayonnement de l&rsquo;Europe continentale se font sans entrave, cette diff\u00e9rence peut atteindre 5 \u00e0 10 degr\u00e9s alors qu&rsquo;en plein oc\u00e9an la m\u00eame diff\u00e9rence est seulement de quelques degr\u00e9s. La raison en est le r\u00e9chauffement diff\u00e9rent des terres et des mers.<br \/>\nLa temp\u00e9rature atmosph\u00e9rique a \u00e9galement une \u00e9volution annuelle. On trouvera dans le tableau ci-dessous des exemples de diff\u00e9rences entre les oc\u00e9ans et les continents.<\/p>\n<p>&nbsp;<\/p>\n<\/div><table border=\"1\" width=\"98%\" bordercolordark=\"#FFFFFF\" cellspacing=\"0\" cellpadding=\"0\">\n  <tr>\n    <td width=\"33%\" align=\"center\" bgcolor=\"#F0F0F0\"><font color=\"#000040\" face=\"Verdana\" size=\"2\"><b>Lieux\n    d'observation<\/b><\/font><\/td>\n    <td width=\"33%\" align=\"center\" bgcolor=\"#F0F0F0\"><font color=\"#000040\" face=\"Verdana\" size=\"2\"><b>Temp\u00e9ratures<\/b><\/font><\/td>\n    <td width=\"34%\" align=\"center\" bgcolor=\"#F0F0F0\"><font color=\"#000040\" face=\"Verdana\" size=\"2\"><b>moyennes<\/b><\/font><\/td>\n  <\/tr>\n  <tr>\n    <td width=\"33%\" bgcolor=\"#F0F0F0\"><font face=\"Verdana\" size=\"2\">\u00a0<\/font><\/td>\n    <td width=\"33%\" align=\"center\" bgcolor=\"#F0F0F0\"><font color=\"#000040\" face=\"Verdana\" size=\"2\">janvier<\/font><\/td>\n    <td width=\"34%\" align=\"center\" bgcolor=\"#F0F0F0\"><font color=\"#000040\" face=\"Verdana\" size=\"2\">juillet<\/font><\/td>\n  <\/tr>\n  <tr>\n    <td width=\"33%\" align=\"center\" bgcolor=\"#F0F0F0\"><font color=\"#000040\" face=\"Verdana\" size=\"2\">Lakoust\n    (Sib\u00e9rie)<\/font><\/td>\n    <td width=\"33%\" align=\"center\" bgcolor=\"#F0F0F0\"><font color=\"#000040\" face=\"Verdana\" size=\"2\">-\n    42,9\u00b0C<\/font><\/td>\n    <td width=\"34%\" align=\"center\" bgcolor=\"#F0F0F0\"><font color=\"#000040\" face=\"Verdana\" size=\"2\">+\n    18,8\u00b0C<\/font><\/td>\n  <\/tr>\n  <tr>\n    <td width=\"33%\" align=\"center\" bgcolor=\"#F0F0F0\"><font color=\"#000040\" face=\"Verdana\" size=\"2\">Thorshavn\n    (\u00eeles F\u00e9ro\u00e9)<\/font><\/td>\n    <td width=\"33%\" align=\"center\" bgcolor=\"#F0F0F0\"><font color=\"#000040\" face=\"Verdana\" size=\"2\">+3,2\u00b0<\/font><\/td>\n    <td width=\"34%\" align=\"center\" bgcolor=\"#F0F0F0\"><font color=\"#000040\" face=\"Verdana\" size=\"2\">+\n    10,8\u00b0C<\/font><\/td>\n  <\/tr>\n<\/table>\n\n<div class=\"fusion-text fusion-text-8\"><h5>L&rsquo;humidit\u00e9 atmosph\u00e9rique<\/h5>\n<p>La mesure de l&rsquo;humidit\u00e9 relative de l&rsquo;air est faite \u00e0 l&rsquo;aide de deux types d&rsquo;appareils dont le principe est diff\u00e9rent, \u00e0 savoir :<\/p>\n<p>1) HYGROM\u00c8TRE \u00c0 CHEVEU : Cet instrument fait appel \u00e0 la propri\u00e9t\u00e9 qu&rsquo;ont les cheveux humains (de pr\u00e9f\u00e9rence f\u00e9minins), et m\u00eame certaines fibres naturelles et artificielles, de s&rsquo;allonger \u00e0 l&rsquo;air humide et de se r\u00e9tracter \u00e0 l&rsquo;air sec. Les diff\u00e9rences de longueur sont amplifi\u00e9es et transmises par des leviers \u00e0 une aiguille, sur un cadran gradu\u00e9 de 0 \u00e0 100 % d&rsquo;humidit\u00e9 atmosph\u00e9rique relative. Pour v\u00e9rifier l&rsquo;exactitude d&rsquo;un appareil de ce type, on l&rsquo;enroule dans un chiffon mouill\u00e9, et on r\u00e8gle son aiguille pour 95 % d&rsquo;humidit\u00e9 au cadran. Par temps de brouillard intense, l&rsquo;hygrom\u00e8tre \u00e0 cheveu doit indiquer une humidit\u00e9 de 100 %.<\/p>\n<p>2) LE PSYCHROM\u00c8TRE : Le principe de cet appareil r\u00e9side en ce que l&rsquo;air sec active l&rsquo;\u00e9vaporation, tandis que l&rsquo;air humide la freine. Il s&rsquo;agit de deux thermom\u00e8tres \u00e0 \u00e9talonnage identique. La boule de l&rsquo;un d&rsquo;eux est entour\u00e9e d&rsquo;une bande d&rsquo;ouate pouvant \u00eatre imbib\u00e9e et dont une extr\u00e9mit\u00e9 trempe dans un r\u00e9cipient plein d&rsquo;eau ; l&rsquo;ouate. est ainsi toujours mouill\u00e9e et l&rsquo;eau s&rsquo;\u00e9vapore en permanence, la boule \u00e9tant expos\u00e9e \u00e0 l&rsquo;air. Il faut pour cela que de la chaleur \u00a0\u00bb actionne \u00a0\u00bb ce thermom\u00e8tre \u00a0\u00bb humide \u00ab\u00a0, lequel indique une temp\u00e9rature inf\u00e9rieure \u00e0 celle de l&rsquo;autre, qui est \u00a0\u00bb sec \u00ab\u00a0. La diff\u00e9rence de temp\u00e9rature observ\u00e9e permet de calculer l&rsquo;humidit\u00e9 relative avec une bonne approximation, \u00e0 l&rsquo;aide de \u00a0\u00bb tables psychrom\u00e9triques \u00ab\u00a0. Par exemple, la diff\u00e9rence tombe \u00e0 0&Prime; lorsque l&rsquo;humidit\u00e9 relative atteint 100 %.<\/p>\n<p>Il convient alors de faire la diff\u00e9rence entre l&rsquo;humidit\u00e9 absolue et l&rsquo;humidit\u00e9 relative. Tout le monde sait que, lorsque l&rsquo;air s&rsquo;humidifie, il s&rsquo;enrichit en vapeur d&rsquo;eau. Cela est visible seulement lorsque l&rsquo;air, satur\u00e9 de vapeur d&rsquo;eau, laisse celle-ci se condenser, sous forme de nuages, de brouillard et de pr\u00e9cipitations.<\/p>\n<p>La temp\u00e9rature joue aussi un r\u00f4le dans le ph\u00e9nom\u00e8ne. Le refroidissement de l&rsquo;air provoque une condensation, \u00e9tant donn\u00e9 que l&rsquo;atmosph\u00e8re peut, \u00e0 une temp\u00e9rature donn\u00e9e, laisser se former une quantit\u00e9 d\u00e9finie de vapeur. En voici un exemple :<br \/>\nDe l&rsquo;air chaud et humide monte. Sa temp\u00e9rature atteint 25\u00b0C pour une quantit\u00e9 de vapeur d&rsquo;eau de 15 grammes par m\u00e8tre cube. Cela signifie une humidit\u00e9 relative de 65 %. Lorsque cet air se refroidit \u00e0 20\u00b0C, son humidit\u00e9 relative s&rsquo;\u00e9l\u00e8ve \u00e0 87 % environ. Des nuages se formeront \u00e0 une altitude o\u00f9 la temp\u00e9rature sera encore de 17\u00b0 ou 18\u00b0C (niveau de sonde condensation, seuil de point de ros\u00e9e). L&rsquo;air montant se refroidit (aussi longtemps que la vapeur d&rsquo;eau ne se condense pas) \u00e0 raison de 1\u00b0C tous les 100 m d&rsquo;altitude (air non satur\u00e9). Dans le pr\u00e9sent exemple, la formation de nuages aura donc lieu \u00e0 une altitude de 700 \u00e0 800 m. Par temps ensoleill\u00e9, l&rsquo;air proche du sol se r\u00e9chauffe de plus en plus au cours de la journ\u00e9e. Il \u00a0\u00bb s&rsquo;\u00e9l\u00e8ve \u00a0\u00bb et devient progressivement plus l\u00e9ger que l&rsquo;air froid au-dessus de lui. Son aptitude \u00e0 attendre l&rsquo;altitude \u00e0 laquelle existe son niveau de condensation d\u00e9pend de la temp\u00e9rature de \u00a0\u00bb d\u00e9gagement \u00ab\u00a0. L&rsquo;\u00e9valuation de cette temp\u00e9rature est tr\u00e8s utile pour la connaissance de l&rsquo;\u00e9volution de la temp\u00e9rature et de l&rsquo;humidit\u00e9 des couches sup\u00e9rieures de l&rsquo;atmosph\u00e8re. Cela est indispensable pour les voyages a\u00e9riens et les pr\u00e9visions de vol. Comme la pression et la temp\u00e9rature atmosph\u00e9riques, l&rsquo;humidit\u00e9 subit des modifications quotidiennes. Ainsi, en \u00e9t\u00e9, l&rsquo;humidit\u00e9 relative d&rsquo;un jour chaud est ,faible ; mais elle augmente constamment durant la nuit, et il lui arrive assez souvent d&rsquo;atteindre 100 %, soit le point de ros\u00e9e. Les nuages peuvent s&rsquo;opposer \u00e0 ce ph\u00e9nom\u00e8ne en inhibant le rayonnement nocturne. Le point de ros\u00e9e indique la temp\u00e9rature minima qui doit \u00eatre atteinte au cours d&rsquo;une nuit. Il change \u00e0 condition qu&rsquo;il n&rsquo;y ait pas pendant la nuit de m\u00e9lange des masses d&rsquo;air, notamment par arriv\u00e9e d&rsquo;air froid. Lorsque le point de ros\u00e9e est proche de 0\u00b0C, une gel\u00e9e nocturne est \u00e0 craindre. Une humidit\u00e9 relative \u00e9lev\u00e9e lors d&rsquo;une nuit \u00e9toil\u00e9e fait pr\u00e9voir la formation de brouillard ; mais lorsqu&rsquo;elle est faible dans les m\u00eames conditions, le refroidissement doit s&rsquo;accentuer. Il convient d&rsquo;observer, en ce qui concerne les temp\u00e9ratures minima au sol, qu&rsquo;il se forme de la gel\u00e9e blanche m\u00eame si la temp\u00e9rature sous abri d\u00e9passe l\u00e9g\u00e8rement 0\u00b0C. Les gel\u00e9es blanches se forment plus facilement dans les creux de terrain. L&rsquo;\u00e9valuation du point de ros\u00e9e est tr\u00e8s important pour la pr\u00e9vision des gel\u00e9es nocturnes (gel\u00e9es blanches). Les mesures doivent \u00eatre effectu\u00e9es normalement juste apr\u00e8s le coucher du Soleil. On trouvera dans le tableau ci-dessous les correspondances entre l&rsquo;humidit\u00e9 et la temp\u00e9rature atmosph\u00e9rique concernant les principaux ph\u00e9nom\u00e8nes du temps.<\/p>\n<\/div><div class=\"fusion-image-element \" style=\"text-align:center;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-2 hover-type-none\"><img decoding=\"async\" width=\"478\" height=\"564\" alt=\"Sch\u00e9ma\" title=\"2024-02-19_08h58_11\" src=\"https:\/\/alertes-meteo.com\/wp-content\/uploads\/2024\/02\/2024-02-19_08h58_11.jpg\" data-orig-src=\"https:\/\/alertes-meteo.com\/wp-content\/uploads\/2024\/02\/2024-02-19_08h58_11.jpg\" class=\"lazyload img-responsive wp-image-14607\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27478%27%20height%3D%27564%27%20viewBox%3D%270%200%20478%20564%27%3E%3Crect%20width%3D%27478%27%20height%3D%27564%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/alertes-meteo.com\/wp-content\/uploads\/2024\/02\/2024-02-19_08h58_11-200x236.jpg 200w, https:\/\/alertes-meteo.com\/wp-content\/uploads\/2024\/02\/2024-02-19_08h58_11-400x472.jpg 400w, https:\/\/alertes-meteo.com\/wp-content\/uploads\/2024\/02\/2024-02-19_08h58_11.jpg 478w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 800px) 100vw, 478px\" \/><\/span><\/div><div class=\"fusion-text fusion-text-9\"><p>.<\/p>\n<\/div><table border=\"1\" cellspacing=\"0\" width=\"98%\" bgcolor=\"#F0F0F0\">\n  <tr>\n    <\/font><td width=\"25%\" align=\"center\"><font face=\"Verdana\" size=\"2\">Temp\u00e9rature<\/font><\/td>\n    <td width=\"25%\" align=\"center\"><font face=\"Verdana\" size=\"2\">Proportion de vapeur<\/font><\/td>\n    <td width=\"25%\" align=\"center\"><font face=\"Verdana\" size=\"2\">Saturation<\/font><\/td>\n    <td width=\"25%\" align=\"center\"><font face=\"Verdana\" size=\"2\">Humidit\u00e9<\/font><\/td>\n    <font size=\"4\">\n  <\/tr>\n  <tr>\n    <\/font><td width=\"25%\" align=\"center\"><font face=\"Verdana\" size=\"2\">croissante<\/font><p><font face=\"Verdana\" size=\"2\">en diminution<\/font><\/td>\n    <td width=\"25%\" align=\"center\"><font face=\"Verdana\" size=\"2\">constante<\/font><p><font face=\"Verdana\" size=\"2\">constante<\/font><\/td>\n    <td width=\"25%\" align=\"center\"><font face=\"Verdana\" size=\"2\">en augmentant<\/font><p><font face=\"Verdana\" size=\"2\">en diminuant<\/font><\/td>\n    <td width=\"25%\" align=\"center\"><font face=\"Verdana\" size=\"2\">air relativement sec<\/font><p><font face=\"Verdana\" size=\"2\">air relativement humide<\/font><\/td>\n    <font size=\"4\">\n  <\/tr>\n<\/table>\n<div class=\"fusion-text fusion-text-10\"><h6>La densit\u00e9 de l&rsquo;atmosph\u00e8re<\/h6>\n<p>Bien que nous soyons \u00e0 l&rsquo;\u00e8re des fus\u00e9es et des satellites artificiels, on se sert encore beaucoup de ballons-sondes et de radiosondes pour l&rsquo;\u00e9tude de la structure de l&rsquo;atmosph\u00e8re, de sa composition et de sa densit\u00e9 en haute altitude. On consid\u00e8re, en fonction des lois physiques, que la densit\u00e9 de l&rsquo;air diminue avec l&rsquo;altitude. Celle-Ci conditionne \u00e9galement la composition de l&rsquo;atmosph\u00e8re, \u00e9tant donn\u00e9 que les gaz<br \/>\nqui la constituent ont des densit\u00e9s diff\u00e9rentes. H\u00e9lium et la vapeur d&rsquo;eau, par exemple, voient leur proportion augmenter, tandis que l&rsquo;azote et l&rsquo;oxyg\u00e8ne se rar\u00e9fient en hauteur.<br \/>\nLa densit\u00e9 de l&rsquo;air joue un grand r\u00f4le, notamment pour les vents. Elle est proportionnelle \u00e0 la pression et inversement proportionnelle \u00e0 la temp\u00e9rature. Dans les pays chauds et pendant les chaleurs estivales, elle peut notablement diminuer. Les avions ont alors besoin de longues pistes et ne doivent as \u00eatre \u00e0 pleine charge.<\/p>\n<ul>\n<li>Calcul de la densit\u00e9 atmosph\u00e9rique :<\/li>\n<\/ul>\n<\/div><div class=\"fusion-image-element \" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-3 hover-type-none\"><img decoding=\"async\" width=\"412\" height=\"33\" title=\"2024-02-19_13h29_23\" src=\"https:\/\/alertes-meteo.com\/wp-content\/uploads\/2024\/02\/2024-02-19_13h29_23.jpg\" data-orig-src=\"https:\/\/alertes-meteo.com\/wp-content\/uploads\/2024\/02\/2024-02-19_13h29_23.jpg\" alt class=\"lazyload img-responsive wp-image-14617\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27412%27%20height%3D%2733%27%20viewBox%3D%270%200%20412%2033%27%3E%3Crect%20width%3D%27412%27%20height%3D%2733%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/alertes-meteo.com\/wp-content\/uploads\/2024\/02\/2024-02-19_13h29_23-200x16.jpg 200w, https:\/\/alertes-meteo.com\/wp-content\/uploads\/2024\/02\/2024-02-19_13h29_23-400x32.jpg 400w, https:\/\/alertes-meteo.com\/wp-content\/uploads\/2024\/02\/2024-02-19_13h29_23.jpg 412w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 800px) 100vw, 412px\" \/><\/span><\/div><div class=\"fusion-text fusion-text-11\"><p><span style=\"color: var(--awb-text-color); font-family: var(--awb-text-font-family); font-size: var(--awb-font-size); font-style: var(--awb-text-font-style); font-weight: var(--awb-text-font-weight); letter-spacing: var(--awb-letter-spacing); text-align: var(--awb-content-alignment); text-transform: var(--awb-text-transform); background-color: var(--awb-bg-color-hover);\">\u00a0<\/span><\/p>\n<p><span style=\"color: var(--awb-text-color); font-family: var(--awb-text-font-family); font-size: var(--awb-font-size); font-style: var(--awb-text-font-style); font-weight: var(--awb-text-font-weight); letter-spacing: var(--awb-letter-spacing); text-align: var(--awb-content-alignment); text-transform: var(--awb-text-transform); background-color: var(--awb-bg-color-hover);\">On sait aujourd&rsquo;hui que, \u00e0 l&rsquo;altitude d&rsquo;environ 100 km, la composition de l&rsquo;atmosph\u00e8re ne varie plus gu\u00e8re. C&rsquo;est pourquoi les ph\u00e9nom\u00e8nes de m\u00e9lange de grande ampleur ont beaucoup d&rsquo;importance, permettant des \u00e9changes gazeux. C&rsquo;est ce qui emp\u00eache la stratification des gaz en fonction de leur densit\u00e9 respective. La densit\u00e9 diminue \u00e0 peu pr\u00e8s parall\u00e8lement \u00e0 la pression en fonction de l&rsquo;altitude. Ainsi, la densit\u00e9 de l&rsquo;air au niveau de la mer est de 1,29 \u00e0 0 \u00b0C (soit par exemple 1,29 g par litre). A 17 km d&rsquo;altitude, elle est encore \u00e9gale &lsquo; au dixi\u00e8me de cette valeur. A partir de 100 km, la diminution de la densit\u00e9, comme celle de la pression, se ralentit. La densit\u00e9 de l&rsquo;atmosph\u00e8re est r\u00e9guli\u00e8rement modifi\u00e9e par les conditions quotidiennes et saisonni\u00e8res, notamment par l&rsquo;insolation. Les produits qui sont en suspension dans l&rsquo;air aux basses altitudes (poussi\u00e8res, fum\u00e9es et autres traces) n&rsquo;influent pas sur la densit\u00e9, alors qu&rsquo;elles ont beaucoup d&rsquo;importance dans la survenance des pr\u00e9cipitations et du brouillard.<\/span><\/p>\n<p>Les courants a\u00e9riens (<a href=\"https:\/\/alertes-meteo.com\/index.php\/2024\/02\/16\/vent-de-terre-et-vent-de-mer\/\">les vents<\/a>)<\/p>\n<p>Pour appr\u00e9cier la direction du vent, on peut avoir recours \u00e0 une simple \u00a0\u00bb manche \u00e0 air \u00ab\u00a0, facile \u00e0 fabriquer. Il s&rsquo;agit d&rsquo;un sac en tissu l\u00e9ger, de forme conique, dont l&rsquo;ouverture est maintenue b\u00e9ante par un cercle en fil de fer, et dont le fond est perc\u00e9. On fixe la manche \u00e0 air au bout d&rsquo;un long m\u00e2t, soit dans un terrain d\u00e9gag\u00e9, soit sur un toit. Il suffit de voir de quel c\u00f4t\u00e9 elle flotte pour conna\u00eetre la direction dans laquelle le vent souffle. Il y a tr\u00e8s longtemps qu&rsquo;on a invent\u00e9 la girouette, qui indique elle aussi la direction du vent. On en utilise des mod\u00e8les perfectionn\u00e9s en m\u00e9t\u00e9orologie, qui sont reli\u00e9s \u00e0 un enregistreur \u00e0 tambour par un syst\u00e8me de transmission m\u00e9canique ou \u00e9lectrique.<br \/>\nLa mesure de la vitesse du vent est effectu\u00e9e suivant plusieurs syst\u00e8mes. L&rsquo;appareil habituel est l&rsquo;an\u00e9mom\u00e8tre : celui-ci est constitu\u00e9 par des coquilles h\u00e9misph\u00e9riques, mont\u00e9es horizontalement au bout de petits bras, ceux-ci \u00e9tant fix\u00e9s sur un axe tournant dans le sens horaire. Plus la vitesse du vent est grande, plus les coquilles (en m\u00e9tal ou en mati\u00e8re plastique) tournent vite. La mesure de la vitesse se fait en fonction du nombre de tours par seconde qu&rsquo;on convertit en m\u00e8tres par seconde \u00e0 l&rsquo;aide d&rsquo;une table. Nombre d&rsquo;an\u00e9mom\u00e8tres donnent cette derni\u00e8re mesure directement sur un cadran, de 0 \u00e0 25 m\u00e8tres par seconde, cet intervalle couvrant une partie de l&rsquo;\u00e9chelle de Beaufort, soit de 0 \u00e0 9 (du calme plat \u00e0 la temp\u00eate).<br \/>\nIl existe bien s\u00fbr toute sorte de syst\u00e8mes m\u00e9caniques et \u00e9lectriques d&rsquo;enregistrement de la vitesse du vent, sur bande ou sur tambour.<\/p>\n<p>La force du vent, habituellement donn\u00e9e en m\u00e8tres par seconde, peut l&rsquo;\u00eatre aussi en km par heure et en milles marins par heure ou en n\u0153uds.<\/p>\n<\/div><div class=\"fusion-text fusion-text-12\"><p>L&rsquo;\u00e9chelle de Beaufort, qui comprend 12 degr\u00e9s, est encore plus vaste. La force 12 dans l&rsquo;\u00e9chelle de Beaufort (\u00a0\u00bb ouragan \u00ab\u00a0) correspond \u00e0 une vitesse du vent de plus de 120 km \u00e0 l&rsquo;heure. On observe des vitesses encore plus grandes lors des fortes temp\u00eates (plus de 200 km \u00e0 l&rsquo;heure), par exemple lors des typhons de la mer de Chine. On n&rsquo;oubliera pas qu&rsquo;il s&rsquo;agit pour ces mesures des conditions au sol. La vitesse du vent est bien sup\u00e9rieure aux hautes altitudes : la troposph\u00e8re est parcourue par des \u00a0\u00bb jet streams \u00a0\u00bb dont la vitesse atteint 400 km l&rsquo;heure, bien connus dans les transports a\u00e9riens internationaux. Les vents soufflent d&rsquo;une zone de haute pression \u00e0 une zone de basse pression, comme nous l&rsquo;avons dit. La force du vent est \u00e9videmment li\u00e9e aux diff\u00e9rences de pression atmosph\u00e9rique. Un vent souffle d&rsquo;autant plus fort que cette diff\u00e9rence est plus grande et que la distance entre deux zones \u00e0 pressions diff\u00e9rentes est plus petite.<br \/>\nPlus le \u00a0\u00bb gradient \u00a0\u00bb est important, plus la vitesse du vent est grande. Les diff\u00e9rences de pression se constituent quotidiennement en fonction des masses d&rsquo;air \u00e0 des temp\u00e9ratures diff\u00e9rentes. On observera en outre que l&rsquo;air continental se r\u00e9chauffe plus vite que l&rsquo;air marin. La diff\u00e9rence de pression d\u00e9termine seulement pour les courants locaux la force et la direction des vents. Les grands courants a\u00e9riens sont dus au r\u00e9chauffement in\u00e9gal des masses d&rsquo;air et ils d\u00e9vient en fonction de la rotation de la Terre. La d\u00e9viation pr\u00e9sente un maximum sous les latitudes moyennes (par exemple en Europe). Elle est nulle \u00e0 l&rsquo;\u00e9quateur et augmente en m\u00eame temps que la latitude. Enfin, elle est fonction de la vitesse du vent.<br \/>\nLa d\u00e9viation des vents ob\u00e9it \u00e0 la \u00a0\u00bb loi de Coriolis \u00a0\u00bb (du nom du physicien fran\u00e7ais Coriolis, 1792-1843) : un corps en mouvement est d\u00e9vi\u00e9 de son trajet, lorsque son mouvement est li\u00e9 par une force d&rsquo;inertie (force de Coriolis) \u00e0 la rotation d&rsquo;un autre corps. La force de Coriolis est la cause des aliz\u00e9s.<br \/>\nLes vents au sol subissent une d\u00e9viation et un freinage, dus aux frottements de l&rsquo;air sur la surface terrestre. Pour leur part, les montagnes font barrage aux vents, en les faisant monter ou d\u00e9vier.<br \/>\nEn r\u00e9sum\u00e9, la force du vent d\u00e9pend des facteurs suivants :<\/p>\n<p>&nbsp;<\/p>\n<ol>\n<li><span style=\"color: #f4360c;\">Le profil horizontal de la pression atmosph\u00e9rique (grandeur du gradient). <\/span><\/li>\n<li><span style=\"color: #f4360c;\">La latitude (force de Coriolis). <\/span><\/li>\n<li><span style=\"color: #f4360c;\">Les pertes d&rsquo;\u00e9nergie par frottements au sol. <\/span><\/li>\n<li><span style=\"color: #f4360c;\">La d\u00e9viation du trajet.<\/span><\/li>\n<\/ol>\n<p>Il existe au sol toute sorte de vents et de syst\u00e8mes de vents, d\u00e9termin\u00e9s par la d\u00e9viation due \u00e0 la rotation de la Terre (aliz\u00e9s), \u00e0 la diff\u00e9rence de r\u00e9chauffement de l&rsquo;air sur les terres et les mers (moussons), et au relief terrestre (f\u0153hn)<\/p>\n<div>\n<p>Les vents sont indiqu\u00e9s par des fl\u00e8ches sur les cartes du temps. Ces fl\u00e8ches sont constitu\u00e9es ainsi : un cercle indique l&#8217;emplacement de la station (il peut en plus pr\u00e9senter des secteurs blancs plus ou moins importants en fonction de la ,n\u00e9bulosit\u00e9 ; voir les tableaux plus loin) ; de ce cercle part un segment orient\u00e9 dans la direction du vent ; enfin, ce segment porte un \u00a0\u00bb empennage \u00a0\u00bb de petits segments, \u00e0 raison d&rsquo;un demi-segment par tranche de vitesse du vent, la force 10 de Beaufort \u00e9tant indiqu\u00e9e par un triangle.<\/p>\n<\/div>\n<\/div><div class=\"fusion-text fusion-text-13\"><p>&nbsp;<\/p>\n<p>En r\u00e9sum\u00e9<\/p>\n<p>La masse de l&rsquo;atmosph\u00e8re exerce une pression moyenne de 1 013 millibars (mb) sur la surface terrestre. Au niveau de la mer, les variations de pression peuvent atteindre 50 mb au cours d&rsquo;une m\u00eame journ\u00e9e, mais nous n&rsquo;y sommes pas sensibles, sauf si elles sont tr\u00e8s soudaines. La pression de l&rsquo;air diminue avec l&rsquo;altitude, l&rsquo;atmosph\u00e8re se rar\u00e9fiant. Jusqu&rsquo;\u00e0 une altitude de 1 000 m, elle chute d&rsquo;environ 1 mb tous les 10 m et \u00e0 5,5 km d&rsquo;altitude, elle est d&rsquo;environ 500 mb, soit de moiti\u00e9 inf\u00e9rieure \u00e0 la pression relev\u00e9e au sol.<\/p>\n<p>Ce sont les variations horizontales de la pression atmosph\u00e9rique qui engendrent les vents, l&rsquo;air s&rsquo;\u00e9coulant d&rsquo;une zone de haute pression vers une zone de basse pression. La diminution verticale de la pression a d&rsquo;importants effets sur les propri\u00e9t\u00e9s de l&rsquo;air. Une masse d&rsquo;air qui est amen\u00e9e \u00e0 s&rsquo;\u00e9lever subit une pression de plus en plus faible et se dilate. L&rsquo;air se refroidit en se dilatant. Inversement, une masse d&rsquo;air descendante subit une pression croissante. Cette compression s&rsquo;accompagne d&rsquo;un \u00e9chauffement. Cet \u00e9chauffement et ce refroidissement de l&rsquo;air dus aux seules variations de pression sont qualifi\u00e9s d&rsquo;adiabatiques. Ils jouent un r\u00f4le essentiel dans bien des ph\u00e9nom\u00e8nes m\u00e9t\u00e9orologiques.<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"none","_seopress_titles_title":"Tout savoir sur la pression atmosph\u00e9rique et ses impacts","_seopress_titles_desc":"D\u00e9couvrez l&#039;importance de la pression atmosph\u00e9rique et comment elle affecte les conditions m\u00e9t\u00e9orologiques. Consultez notre article pour en savoir plus!","_seopress_robots_index":"","_seopress_analysis_target_kw":"pression atmosph\u00e9rique","footnotes":""},"categories":[132],"tags":[],"class_list":["post-14599","post","type-post","status-publish","format-standard","hentry","category-phenomenes-meteo"],"_links":{"self":[{"href":"https:\/\/alertes-meteo.com\/index.php\/wp-json\/wp\/v2\/posts\/14599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alertes-meteo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alertes-meteo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alertes-meteo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/alertes-meteo.com\/index.php\/wp-json\/wp\/v2\/comments?post=14599"}],"version-history":[{"count":0,"href":"https:\/\/alertes-meteo.com\/index.php\/wp-json\/wp\/v2\/posts\/14599\/revisions"}],"wp:attachment":[{"href":"https:\/\/alertes-meteo.com\/index.php\/wp-json\/wp\/v2\/media?parent=14599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alertes-meteo.com\/index.php\/wp-json\/wp\/v2\/categories?post=14599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alertes-meteo.com\/index.php\/wp-json\/wp\/v2\/tags?post=14599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}